{"id":3386,"date":"2023-12-07T19:25:20","date_gmt":"2023-12-07T22:25:20","guid":{"rendered":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/"},"modified":"2023-12-10T12:40:33","modified_gmt":"2023-12-10T15:40:33","slug":"con-la-mira-en-el-10-d","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/","title":{"rendered":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones"},"content":{"rendered":"<p><em>Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el corto plazo), en la semana se advirti\u00f3 una ligera mayor incertidumbre: el BCRA intensific\u00f3 su ritmo de ventas y la brecha cambiaria mostr\u00f3 un fuerte salto en las \u00faltimas ruedas, aunque\u00a0los futuros del d\u00f3lar se mantuvieron relativamente estables.<br \/>\n<\/em><\/p>\n<p><em>Los bancos continuaron renovando un bajo porcentaje de los vencimientos de las LELIQ, redireccionando la liquidez remanente mayormente hacia Pases pasivos. Si bien la \u201cbola de LELIQ\u201d (vencimientos a 28 d\u00edas) se ha transformado paulatinamente en una \u201cbola de Pases\u201d (con vencimientos diarios), hasta el momento no representa m\u00e1s que una maniobra precautoria de los bancos que achican balances ante la incertidumbre generada por la \u201csoluci\u00f3n de mercado\u201d que el presidente electo declar\u00f3 que emplear\u00eda para resolver este frente. \u00bfLa reuni\u00f3n de hace dos semanas con el pr\u00f3ximo ministro de Econom\u00eda, Luis Caputo, no despej\u00f3 inquietudes?<br \/>\n<\/em><\/p>\n<p><em>A partir del inicio de gesti\u00f3n del pr\u00f3ximo gobierno, nuestros escenarios incorporan que la unificaci\u00f3n cambiaria llegar\u00eda en alg\u00fan momento de 2024. No obstante, en diciembre la nueva administraci\u00f3n buscar\u00eda comenzar a eliminar algunas regulaciones\/restricciones sobre el mercado cambiario para comenzar a dar se\u00f1ales favorables, lo cual podr\u00eda venir acompa\u00f1ado de una correcci\u00f3n cambiaria (\u00bfsigue el Impuesto Pa\u00eds?), sobre la base de que la mayor parte de la econom\u00eda ya viene operando con un tipo de cambio efectivo mayor.\u00a0 Con todo, ser\u00e1 fundamental que aquellas correcciones iniciales est\u00e9n acompa\u00f1as por un conjunto de medidas enmarcadas en un programa de estabilizaci\u00f3n t\u00e9cnicamente s\u00f3lido, cre\u00edble y con apoyo pol\u00edtico.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de <strong>novedades y movimientos de cobertura<\/strong> frente al inicio de la nueva gesti\u00f3n presidencial desde este domingo 10 de diciembre.<\/p>\n<p><strong>1)<\/strong> <strong>El BCRA increment\u00f3 sus ventas netas en el MULC:<\/strong> La intensificaci\u00f3n de la demanda y la escasa oferta de USD llevaron a las autoridades actuales a incrementar el ritmo de ventas para sostener el <em>crawling peg<\/em> del tipo de cambio, acumulado as\u00ed ventas netas por USD 570 M en las \u00faltimas 6 ruedas.<\/p>\n<p><strong>2)<\/strong> El BCRA sigui\u00f3 convalidando un <strong><em>crawling peg<\/em> <\/strong>del tipo de cambio oficial a un ritmo mensualizado del 4,3%, finalizando as\u00ed el mandato de Alberto Fern\u00e1ndez con una cotizaci\u00f3n en torno de los $364. Como resultado, el d\u00f3lar oficial sufri\u00f3 desde el viernes previo a las PASO una apreciaci\u00f3n superior al 9% en t\u00e9rminos reales (pese al salto discreto inicial), y un 30% en toda la gesti\u00f3n de gobierno, lo cual exigir\u00e1 necesariamente una correcci\u00f3n en el corto plazo.<\/p>\n<p><strong>3)<\/strong> Los <strong>futuros de d\u00f3lar se mostraron relativamente estables<\/strong> en las \u00faltimas ruedas. De tal forma, el tipo de cambio contenido en el contrato de diciembre termin\u00f3 pr\u00e1cticamente en los mismos niveles que la semana previa ($752-$755), con una devaluaci\u00f3n mensual impl\u00edcita del 107%. Estos valores reflejan que el mercado no est\u00e1 poniendo en precios una unificaci\u00f3n cambiaria para este mes que logre cerrar la brecha.<\/p>\n<p><strong>4)<\/strong> Los <strong>USD alternativos mostraron un fuerte repunte en las \u00faltimas ruedas, volviendo a tocar m\u00e1ximos nominales. <\/strong>Consecuentemente, la brecha promedio roz\u00f3 el 175%, similar a los niveles de crisis posteriores a la primera vuelta.<strong> \u00bfCu\u00e1l podr\u00eda ser la explicaci\u00f3n del salto repentino? <\/strong>Estimamos que este mayor nerviosismo podr\u00eda responder a la incertidumbre en torno a la viabilidad de la implementaci\u00f3n del ambicioso plan fiscal-monetario de Milei para lograr una estabilizaci\u00f3n, frente a los enormes desaf\u00edos econ\u00f3micos, pol\u00edticos y sociales por delante.<\/p>\n<p><strong>5)<\/strong> <strong>Los bancos continuaron renovando un bajo porcentaje de los vencimientos de las LELIQ,<\/strong> redireccionando la liquidez remanente principalmente hacia Pases pasivos para reducir la duraci\u00f3n de sus activos (vencimiento a 1 d\u00eda en lugar de 28, a costa de una leve p\u00e9rdida en la rentabilidad), producto de la incertidumbre sobre la \u201csoluci\u00f3n de mercado\u201d que el presidente electo emplear\u00eda como condici\u00f3n necesaria para levantar el cepo cambiario. Como resultado, los \u00faltimos datos disponibles muestran que actualmente el <em>stock<\/em> de Pases ya representar\u00eda el 73% de los pasivos remunerados, cuando a mediados de noviembre rozaba el 40%.<\/p>\n<p>Con respecto al \u00faltimo punto, si bien la <strong>\u201cbola de LELIQ\u201d<\/strong> se transform\u00f3 paulatinamente en una <strong>\u201cbola de Pases\u201d<\/strong> con vencimiento diario, hasta el momento no es m\u00e1s que una maniobra precautoria de los bancos ante la incertidumbre generada. Sin embargo, el <em>stock<\/em> de plazos fijos privados cay\u00f3 m\u00e1s de $780.000 M desde el 13\/11, aunque dicha ca\u00edda es insignificante frente a la reducci\u00f3n de las LELIQ durante el mismo periodo (-$7,3 billones sin contemplar las ca\u00eddas del 6 y 7 de diciembre).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-16019 size-full\" src=\"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/Tablero-LELIQ-y-Pases-1.png\" alt=\"\" width=\"1600\" height=\"900\" \/><\/p>\n<p>Como mencionamos en m\u00e1s de una oportunidad, la gravedad del \u201cproblema de las LELIQ y Pases\u201d depender\u00e1 crucialmente de la postura que adopten los depositantes frente a la incertidumbre. Entonces, <strong>\u00bfqui\u00e9nes son los due\u00f1os de los pesos retenidos en los balances de los bancos?<\/strong> Si tomamos la totalidad de los dep\u00f3sitos en moneda nacional del sector privado (no financiero), <strong>de cada $100:<\/strong> $42 corresponden a personas f\u00edsicas y $58 a personas jur\u00eddicas. Dentro de estos $58, $27 se encuentran en manos de Fondos Comunes de Inversi\u00f3n (FCI), mientras que el restante pertenece mayormente a empresas (donde $10 son PyMEs).<\/p>\n<p><strong>\u00bfPor qu\u00e9 es importante marcar esta particularidad de los dep\u00f3sitos?<\/strong> Buena parte de aquellos pesos retenidos reflejan directa o indirectamente el capital de trabajo de las empresas, lo cual implica que no podr\u00eda volcarse en tu totalidad a presionar al d\u00f3lar frente a una flexibilizaci\u00f3n de las restricciones vigentes, dado que a\u00fan necesitar\u00edan pesos para operar en el d\u00eda a d\u00eda.<\/p>\n<p>A partir del inicio de gesti\u00f3n del pr\u00f3ximo gobierno, nuestros escenarios incorporan que el desarme completo del cepo cambiario no ser\u00eda la prioridad (a diferencia de 2015) dentro las primeras medidas de la nueva administraci\u00f3n, sino que <strong>la unificaci\u00f3n cambiaria llegar\u00eda en alg\u00fan momento de 2024. <\/strong><\/p>\n<p>No obstante, en diciembre la nueva administraci\u00f3n buscar\u00eda comenzar a eliminar algunas regulaciones\/restricciones sobre el mercado cambiario para comenzar a dar se\u00f1ales favorables, lo cual <strong>podr\u00eda venir acompa\u00f1ado de un salto discreto del tipo de cambio oficial,\u00a0<\/strong>sobre la base de que la mayor parte de la econom\u00eda ya viene operando con un tipo de cambio efectivo mayor.<\/p>\n<p>Claramente, para que la estrategia implementada por el gobierno de Javier Milei tenga cierto nivel de \u00e9xito, ser\u00e1 fundamental que aquellas correcciones iniciales est\u00e9n acompa\u00f1as por un <strong>conjunto de medidas enmarcadas en un programa de estabilizaci\u00f3n t\u00e9cnicamente s\u00f3lido, cre\u00edble y con apoyo pol\u00edtico.<\/strong><\/p>\n<p>Seguramente la semana pr\u00f3xima haya novedades que nos permitan responder al menos algunas de las <strong>numerosas preguntas presentes hoy en d\u00eda:<\/strong> <em>\u00bfcu\u00e1ndo se implementar\u00e1 la correcci\u00f3n cambiaria? \u00bfa qu\u00e9 nivel de tipo de cambio se apunta como norte en t\u00e9rminos reales? \u00bfser\u00e1 \u00fanicamente un salto discreto? \u00bfc\u00f3mo reaccionar\u00e1n los exportadores e importadores? \u00bfqu\u00e9 restricciones se relajar\u00edan? \u00bfcu\u00e1l es el horizonte de unificaci\u00f3n cambiaria? \u00bfHabr\u00e1 un plan de estabilizaci\u00f3n que reviva al Peso, o ser\u00edan medidas contempladas en un plan para dolarizar m\u00e1s adelante?<\/em><\/p>\n<h3>MULC bajo presi\u00f3n, reservas a la baja<\/h3>\n<p><strong>El BCRA intensific\u00f3 su ritmo de ventas en el MULC durante la \u00faltima semana.<\/strong> Puntualmente, la autoridad monetaria vendi\u00f3 USD 377 M en las \u00faltimas 4 ruedas, cuando la semana previa hab\u00eda mostrado un saldo negativo por USD 143 M (con una rueda adicional). Consecuentemente, las Reservas Netas (considerando los DEG pero excluyendo el resto de los pasivos del BCRA) se hundieron a m\u00ednimos hist\u00f3ricos pr\u00f3ximos a los &#8211; USD 11.000 M.<\/p>\n<h3>Brecha cambiaria: fuerte ajuste al alza sobre el final<\/h3>\n<p><strong>Los d\u00f3lares alternativos mostraron un fuerte repunte en las \u00faltimas ruedas, volviendo a tocar m\u00e1ximos nominales.<\/strong> Puntualmente, mientras el blue y el MEP mostraron subas semanales en torno al 3% y 7%, el CCL v\u00eda CEDEAR mostr\u00f3 un incremento del 10%, y el CCL v\u00eda GD30 un salto de casi el 17%. Como resultado, la brecha promedio toc\u00f3 el 173%, casi 15 p.p. por encima del cierre semanal previo (158%).<\/p>\n<h3>Futuros a la espera del lunes<\/h3>\n<p><strong>Los futuros de d\u00f3lar se mostraron relativamente estables<\/strong> en las \u00faltimas ruedas. De tal forma, el tipo de cambio contenido en el contrato a diciembre termin\u00f3 pr\u00e1cticamente en los mismos niveles que la semana previa ($752-$755), con una devaluaci\u00f3n mensual esperada del 107%, consistente con un d\u00f3lar oficial que, a\u00fan con este salto, no lograr\u00eda cerrar la brecha cambiaria (estos precios no descuentan una unificaci\u00f3n en diciembre).<\/p>","protected":false},"excerpt":{"rendered":"<p>Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3392,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Bruno Bonfanti","image_url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/Fondo-cambiario.jpeg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-07T22:25:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-10T15:40:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#blogposting\",\"name\":\"Quiero ver, \\u00bfquiero entrar?: la hora de las definiciones - Ecolatina\",\"headline\":\"Quiero ver, \\u00bfquiero entrar?: la hora de las definiciones\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Fondo-cambiario-2.jpeg\",\"width\":1280,\"height\":842},\"datePublished\":\"2023-12-07T19:25:20-03:00\",\"dateModified\":\"2023-12-10T12:40:33-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#listItem\",\"name\":\"Quiero ver, \\u00bfquiero entrar?: la hora de las definiciones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#listItem\",\"position\":3,\"name\":\"Quiero ver, \\u00bfquiero entrar?: la hora de las definiciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/\",\"name\":\"Quiero ver, \\u00bfquiero entrar?: la hora de las definiciones - Ecolatina\",\"description\":\"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \\u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\\u00f3n (al menos en el\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Fondo-cambiario-2.jpeg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#mainImage\",\"width\":1280,\"height\":842},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#mainImage\"},\"datePublished\":\"2023-12-07T19:25:20-03:00\",\"dateModified\":\"2023-12-10T12:40:33-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","description":"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el","canonical_url":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#blogposting","name":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","headline":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-2.jpeg","width":1280,"height":842},"datePublished":"2023-12-07T19:25:20-03:00","dateModified":"2023-12-10T12:40:33-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#listItem","name":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#listItem","position":3,"name":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#webpage","url":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/","name":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","description":"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-2.jpeg","@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#mainImage","width":1280,"height":842},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/#mainImage"},"datePublished":"2023-12-07T19:25:20-03:00","dateModified":"2023-12-10T12:40:33-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","og:description":"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el","og:url":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/","article:published_time":"2023-12-07T22:25:20+00:00","article:modified_time":"2023-12-10T15:40:33+00:00","twitter:card":"summary_large_image","twitter:title":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","twitter:description":"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una dolarizaci\u00f3n (al menos en el"},"aioseo_meta_data":{"post_id":"3386","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-07 22:40:43","updated":"2025-06-04 01:37:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQuiero ver, \u00bfquiero entrar?: la hora de las definiciones\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones","link":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina\" \/>\n<meta property=\"og:description\" content=\"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-07T22:25:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-10T15:40:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"842\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones\",\"datePublished\":\"2023-12-07T22:25:20+00:00\",\"dateModified\":\"2023-12-10T15:40:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/\"},\"wordCount\":1515,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Fondo-cambiario-2.jpeg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/\",\"name\":\"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Fondo-cambiario-2.jpeg\",\"datePublished\":\"2023-12-07T22:25:20+00:00\",\"dateModified\":\"2023-12-10T15:40:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Fondo-cambiario-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Fondo-cambiario-2.jpeg\",\"width\":1280,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2023\\\/12\\\/07\\\/con-la-mira-en-el-10-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/","og_locale":"en_US","og_type":"article","og_title":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","og_description":"Como suele suceder en la previa a un evento disruptivo esperado por el mercado, la \u00faltima semana estuvo cargada de novedades y movimientos de cobertura frente al inicio de la nueva gesti\u00f3n presidencial desde el domingo 10 de diciembre (10-D). Si bien el mercado sigue sin poner en precios una [&hellip;]","og_url":"https:\/\/ecolatina.com\/en\/2023\/12\/07\/con-la-mira-en-el-10-d\/","og_site_name":"Ecolatina","article_published_time":"2023-12-07T22:25:20+00:00","article_modified_time":"2023-12-10T15:40:33+00:00","og_image":[{"width":1280,"height":842,"url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-1.jpeg","type":"image\/jpeg"}],"author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones","datePublished":"2023-12-07T22:25:20+00:00","dateModified":"2023-12-10T15:40:33+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/"},"wordCount":1515,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-2.jpeg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/","url":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/","name":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-2.jpeg","datePublished":"2023-12-07T22:25:20+00:00","dateModified":"2023-12-10T15:40:33+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-2.jpeg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/12\/Fondo-cambiario-2.jpeg","width":1280,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2023\/12\/07\/con-la-mira-en-el-10-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Quiero ver, \u00bfquiero entrar?: la hora de las definiciones"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=3386"}],"version-history":[{"count":3,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3386\/revisions"}],"predecessor-version":[{"id":3393,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3386\/revisions\/3393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/3392"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=3386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=3386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=3386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}