{"id":3495,"date":"2024-02-14T00:07:48","date_gmt":"2024-02-14T03:07:48","guid":{"rendered":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/"},"modified":"2024-02-14T00:08:16","modified_gmt":"2024-02-14T03:08:16","slug":"otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","title":{"rendered":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo"},"content":{"rendered":"<p><em>Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en t\u00e9rminos reales del 13,2% en promedio (y -18,9% i.a.).<\/em><\/p>\n<p><em>A lo largo del a\u00f1o la ca\u00edda promedio del salario de la econom\u00eda fue de -3,7% i.a, marcando el sexto a\u00f1o consecutivo de p\u00e9rdida del poder adquisitivo. El deterioro fue com\u00fan a casi todos: los salarios del sector privado registrado cayeron -2,3% i.a. en promedio, mientras que la ca\u00edda lleg\u00f3 a -16,4% i.a. en promedio de los no registrados.<\/em><\/p>\n<p><em>Si bien seguramente veremos sindicatos -en algunos casos importantes- que lograr\u00e1n acuerdos virtualmente indexados a la inflaci\u00f3n pasada, no esperamos que esto sea un fen\u00f3meno generalizado. El resultado ser\u00e1 una continuidad del deterioro del poder adquisitivo a lo largo del verano, que estimamos ser\u00e1 de superior a 10% pero que adem\u00e1s profundizar\u00e1 la disparidad salarial entre distintos sectores.<\/em><\/p>\n<h3>\u00bfC\u00f3mo cerraron el a\u00f1o los salarios de la econom\u00eda?<\/h3>\n<p>El INDEC inform\u00f3 que los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la <em>performance<\/em> de los salarios del sector formal (9,0%) e informal (7,6%), <strong>los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre<\/strong>, que ascendi\u00f3 al 25,5%, sufriendo una <strong>ca\u00edda de magnitud hist\u00f3rica<\/strong>: en diciembre los salarios sufrieron una p\u00e9rdida mensual en t\u00e9rminos reales del 13,2% en promedio (y -18,9% i.a.), retrocediendo 20,5% entre agosto y diciembre. Tomando como base el dato de los salarios privados de trabajadores estables (RIPTE), cuya serie disponible es m\u00e1s extensa, <strong>la contracci\u00f3n mensual fue la m\u00e1s importante de la serie que se inicia en 1994<\/strong>, dando cuenta de un salario real que volvi\u00f3 a niveles de septiembre 2003.<\/p>\n<p>De este modo, a lo largo del a\u00f1o la ca\u00edda promedio del salario de la econom\u00eda fue de -3,7% i.a, marcando el <strong>sexto a\u00f1o consecutivo de p\u00e9rdida del poder adquisitivo<\/strong>. El deterioro fue com\u00fan a casi todos: los salarios del <strong>sector privado registrado<\/strong> cayeron -2,3% i.a. en promedio, mientras que la ca\u00edda lleg\u00f3 a -16,4% i.a. en promedio de los <strong>no registrados<\/strong>. De todas maneras, los salarios del <strong>sector p\u00fablico<\/strong> mostraron una estabilidad en el promedio de 2023 (+1,1% i.a.). Vale decir que, en el caso de los trabajadores informales, el salario publicado tiene un rezago de aproximadamente 5 meses, por lo que la ca\u00edda resulta m\u00e1s abultada, ya que la mayor nominalidad de la econom\u00eda en general no se ve plasmada en estos salarios. No obstante, hasta julio, el per\u00edodo comparable, la perdida era en torno a 13%, ya significativamente mayor que la de los trabajadores registrados (una estabilidad de 0,5% en aquel momento).<\/p>\n<p>En suma, no se logr\u00f3 poner plata en el bolsillo de la gente, y tomando como referencia los cuatro a\u00f1os del gobierno del <strong>Frente de Todos, <\/strong>el salario real de la econom\u00eda cay\u00f3 alrededor de 11%. Si sumamos los cuatro a\u00f1os previos de <strong>Cambiemos<\/strong>, el deterioro supera 25%. No ser\u00e1 2024 un a\u00f1o en que esto se revierta.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-16364 size-large\" src=\"http:\/\/lh3.googleusercontent.com\/DhEPo7xE2hragcH2WKWO8ouSGXpZp6-azIDT1UF4mOl6XuTvEFB5gH7w3enhbN8mnN9kPmiqrUruWZ9hiTH4NYhyU722k8cn_q8EUqk=s1024\" alt=\"\" width=\"1024\" height=\"1024\" \/><\/p>\n<h3>\u00bfQu\u00e9 esperamos para 2024?<\/h3>\n<p>El <em>shock<\/em> nominal que signific\u00f3 la devaluaci\u00f3n y que continuar\u00e1 con las sucesivas subas de tarifas y precios Regulados se trasladar\u00e1 a la din\u00e1mica salarial. Sin embargo, la fuerte recesi\u00f3n actuar\u00e1 moderando las demandas salariales. Si bien seguramente veremos sindicatos -en algunos casos importantes- que lograr\u00e1n acuerdos virtualmente indexados a la inflaci\u00f3n pasada, no esperamos que esto sea un fen\u00f3meno generalizado. El resultado ser\u00e1 una <strong>continuidad del deterioro del poder adquisitivo a lo largo del verano<\/strong>, que estimamos ser\u00e1 de superior a 10% pero que adem\u00e1s profundizar\u00e1 la disparidad salarial entre distintos sectores.<\/p>\n<p>Una <strong>segunda lectura<\/strong> de este fen\u00f3meno es que la ausencia de una pauta salarial por parte del Gobierno busca paritarias libres que <strong>favorezcan a los trabajadores de sectores m\u00e1s productivos<\/strong>, que pueden seguir pagando salarios relativamente altos. Si la recesi\u00f3n \u2013 y la eventual mayor competencia\u2013 no permite el traslado a precios en alg\u00fan sector en particular, la remuneraci\u00f3n de dicho sector ser\u00e1 menor y se convertir\u00e1 en una se\u00f1al para que los trabajadores busquen otros empleos mejores pagos. La liberaci\u00f3n de los precios tambi\u00e9n tiene este aspecto, y busca que los precios -en este caso los salarios- sean informativos acerca de que tan productivo para una sociedad es un determinado sector.<\/p>\n<p>Por este motivo, empezaremos a ver cierta <strong>disociaci\u00f3n entre el derrotero del salario real hac\u00eda dentro de los trabajadores registrados<\/strong>. Los <strong>privados<\/strong> continuar\u00e1n siguiendo de cerca, con vaivenes, a la inflaci\u00f3n gracias a que la vigencia de las paritarias seguir\u00e1 siendo acotada en ausencia de una pauta salarial, m\u00e1xime considerando un sector sindical que se muestra combativo ante el cambio de aire. Por su parte, los <strong>trabajadores p\u00fablicos<\/strong> sufrir\u00e1n un deterioro mayor producto del ahorro del gasto que pretender\u00e1 hacer el Gobierno en sus diferentes niveles.<\/p>\n<p>Finalmente, <strong>no prevemos que haya una recuperaci\u00f3n en los trabajadores informales<\/strong>. La ausencia de paritarias y una mayor cantidad de potenciales trabajadores ante la necesidad de apuntalar los ingresos familiares dar\u00e1 espacio para que este grupo absorba la mayor parte del ajuste salarial. En un escenario en donde la ayuda social estar\u00e1 condicionada con los objetivos fiscales del Gobierno, es probable que las dificultades no tarden en aparecer para esta parte de la sociedad.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3497,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Santiago Manoukian","image_url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/salariosinflacionfff.jpg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-14T03:07:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-14T03:08:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#blogposting\",\"name\":\"Otro ciclo presidencial con p\\u00e9rdida del poder adquisitivo - Ecolatina\",\"headline\":\"Otro ciclo presidencial con p\\u00e9rdida del poder adquisitivo\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/salariosinflacionfff-1.jpg\",\"width\":500,\"height\":280},\"datePublished\":\"2024-02-14T00:07:48-03:00\",\"dateModified\":\"2024-02-14T00:08:16-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#listItem\",\"name\":\"Otro ciclo presidencial con p\\u00e9rdida del poder adquisitivo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#listItem\",\"position\":3,\"name\":\"Otro ciclo presidencial con p\\u00e9rdida del poder adquisitivo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/\",\"name\":\"Otro ciclo presidencial con p\\u00e9rdida del poder adquisitivo - Ecolatina\",\"description\":\"Los salarios de la econom\\u00eda crecieron 8,9% mensual en diciembre. M\\u00e1s all\\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\\u00f3n con la inflaci\\u00f3n de diciembre, que ascendi\\u00f3 al 25,5%, sufriendo una ca\\u00edda de magnitud hist\\u00f3rica: en diciembre los salarios sufrieron una p\\u00e9rdida mensual en\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/salariosinflacionfff-1.jpg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#mainImage\",\"width\":500,\"height\":280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#mainImage\"},\"datePublished\":\"2024-02-14T00:07:48-03:00\",\"dateModified\":\"2024-02-14T00:08:16-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","description":"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en","canonical_url":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#blogposting","name":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","headline":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff-1.jpg","width":500,"height":280},"datePublished":"2024-02-14T00:07:48-03:00","dateModified":"2024-02-14T00:08:16-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#listItem","name":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#listItem","position":3,"name":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#webpage","url":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","name":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","description":"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff-1.jpg","@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#mainImage","width":500,"height":280},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#mainImage"},"datePublished":"2024-02-14T00:07:48-03:00","dateModified":"2024-02-14T00:08:16-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","og:description":"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en","og:url":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","article:published_time":"2024-02-14T03:07:48+00:00","article:modified_time":"2024-02-14T03:08:16+00:00","twitter:card":"summary_large_image","twitter:title":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","twitter:description":"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios sufrieron una p\u00e9rdida mensual en"},"aioseo_meta_data":{"post_id":"3495","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-02-14 03:09:35","updated":"2025-06-04 01:43:17","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOtro ciclo presidencial con p\u00e9rdida del poder adquisitivo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo","link":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina\" \/>\n<meta property=\"og:description\" content=\"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T03:07:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T03:08:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo\",\"datePublished\":\"2024-02-14T03:07:48+00:00\",\"dateModified\":\"2024-02-14T03:08:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/\"},\"wordCount\":958,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/salariosinflacionfff-1.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/\",\"name\":\"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/salariosinflacionfff-1.jpg\",\"datePublished\":\"2024-02-14T03:07:48+00:00\",\"dateModified\":\"2024-02-14T03:08:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/salariosinflacionfff-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/salariosinflacionfff-1.jpg\",\"width\":500,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/02\\\/14\\\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","og_locale":"en_US","og_type":"article","og_title":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","og_description":"Los salarios de la econom\u00eda crecieron 8,9% mensual en diciembre. M\u00e1s all\u00e1 de la performance de los salarios del sector formal (9,0%) e informal (7,6%), los aumentos salariales no tuvieron comparaci\u00f3n con la inflaci\u00f3n de diciembre, que ascendi\u00f3 al 25,5%, sufriendo una ca\u00edda de magnitud hist\u00f3rica: en diciembre los salarios [&hellip;]","og_url":"https:\/\/ecolatina.com\/en\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","og_site_name":"Ecolatina","article_published_time":"2024-02-14T03:07:48+00:00","article_modified_time":"2024-02-14T03:08:16+00:00","og_image":[{"width":500,"height":280,"url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff.jpg","type":"image\/jpeg"}],"author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo","datePublished":"2024-02-14T03:07:48+00:00","dateModified":"2024-02-14T03:08:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/"},"wordCount":958,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff-1.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","url":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/","name":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff-1.jpg","datePublished":"2024-02-14T03:07:48+00:00","dateModified":"2024-02-14T03:08:16+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff-1.jpg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/02\/salariosinflacionfff-1.jpg","width":500,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2024\/02\/14\/otro-ciclo-presidencial-con-perdida-del-poder-adquisitivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Otro ciclo presidencial con p\u00e9rdida del poder adquisitivo"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=3495"}],"version-history":[{"count":1,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3495\/revisions"}],"predecessor-version":[{"id":3498,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3495\/revisions\/3498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/3497"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=3495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=3495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=3495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}