{"id":3524,"date":"2024-03-08T19:35:28","date_gmt":"2024-03-08T22:35:28","guid":{"rendered":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/"},"modified":"2024-03-08T19:35:28","modified_gmt":"2024-03-08T22:35:28","slug":"una-semana-con-reacciones-positivas","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","title":{"rendered":"Una semana con reacciones positivas"},"content":{"rendered":"<p><em>En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha cambiaria hil\u00f3 su s\u00e9ptima semana consecutiva a la baja; 2) El BCRA aceler\u00f3 el ritmo de compras en el MULC; 3) Los futuros del d\u00f3lar mostraron un marcado recorte; y 4) Se moder\u00f3 la demanda de la Serie 3 del BOPREAL.<\/em><\/p>\n<p><em>\u00bfCu\u00e1l es el principal riesgo en este contexto? El despertar de la brecha cambiaria generado tanto por la oferta como por la demanda. Por un lado, las pr\u00e1cticamente nulas opciones de inversi\u00f3n para resguardarse frente a los mayores niveles de nominalidad, junto con la vigencia de una tasa de inter\u00e9s sumamente negativa en t\u00e9rminos reales quitan incentivos a ahorrar en pesos. Por ende, un stock de pesos que se encuentra expectante podr\u00eda redireccionarse hacia los d\u00f3lares alternativos, generando as\u00ed una mayor demanda de USD por fuera del MULC.<\/em><\/p>\n<p><em>Paralelamente, si bien los exportadores tienen incentivos a liquidar frente a la continua ca\u00edda en los precios internacionales y el elevado spread entre la tasa de inter\u00e9s y el crawling peg (tasa en 8% mensual contra una devaluaci\u00f3n mensual del 2%), el esquema se considerar\u00e1 sostenible siempre y cuando los tenedores de los USD no perciban que puede ocurrir un nuevo salto discreto del TC oficial en el corto plazo. El ingreso de divisas proveniente de la cosecha gruesa es fundamental para mantener el saldo comprador del BCRA frente a una demanda que paulatinamente se ir\u00e1 incrementando producto del esquema de acceso escalonado. A su vez, una menor liquidaci\u00f3n de exportaciones reducir\u00eda tambi\u00e9n la oferta de USD en los mercados financieros, sumando presiones a la brecha cambiaria.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente.<\/p>\n<p><strong>1) La brecha cambiaria hil\u00f3 su s\u00e9ptima semana consecutiva a la baja<\/strong>. Los USD alternativos mostraron recortes semanales entre un 3% y un 5%. Si bien dicha reducci\u00f3n podr\u00eda explicarse en parte por una menor demanda (producto de la reducci\u00f3n real del stock de pesos y la din\u00e1mica recesiva), sostenemos que el principal motivo ser\u00eda una mayor oferta de divisas proveniente de las liquidaciones por exportaciones que se negocian al CCL (esquema 80%-20%). En consecuencia, la brecha cambiaria promedio se encuentra estable en niveles relativamente bajos (por debajo del 20%), con unos USD alternativos en m\u00ednimos reales para los \u00faltimos a\u00f1os.<\/p>\n<p><strong>2) El BCRA aceler\u00f3 el ritmo de compras en el MULC.<\/strong> En n\u00fameros, la autoridad monetaria adquiri\u00f3 m\u00e1s de USD 1.000 M en las \u00faltimas 5 ruedas, promediando compras diarias por poco m\u00e1s de USD 200 M (marcada mejora contra el promedio de USD 50 M en la semana previa). Como resultado, las compras netas sumar\u00edan m\u00e1s de USD 9.600 M desde el cambio de mandato. \u00bfQu\u00e9 explic\u00f3 el incremento en las compras? Una oferta de exportadores que se sostuvo en niveles elevados y una llamativa ca\u00edda en la demanda de divisas. Ahora bien, este segundo factor podr\u00eda explicarse por 2 motivos: La mayor demanda en las semanas previas se explicaba puntualmente por pagos de deuda de provincias y\/o empresas, lo cual habr\u00eda estado ausente en las \u00faltimas ruedas; o b) Mayores trabas en el acceso a importadores.<\/p>\n<p><strong>3) Los futuros del d\u00f3lar mostraron un marcado recorte. <\/strong>Luego del rebote evidenciado el \u00faltimo viernes en la previa al discurso presidencial, los contratos a futuros del d\u00f3lar evidenciaron fuertes ca\u00eddas en la \u00faltima semana. Puntualmente, los TC impl\u00edcitos en los contratos con vencimiento entre marzo y mayo (los m\u00e1s relevante en cuanto al volumen) mostraron bajas semanales que promediaron el 6%, reflejando una devaluaci\u00f3n esperada para marzo que pas\u00f3 del 10,3% a apenas 3,2%.<\/p>\n<p><strong>4) Se moder\u00f3 la demanda de la Serie 3 del BOPREAL.<\/strong> En la \u00faltima licitaci\u00f3n, el BCRA adjudic\u00f3 VN USD 301 M, un 40% por debajo de lo adjudicado en la licitaci\u00f3n previa, lo cual refleja una moderaci\u00f3n esperable dada la ca\u00edda en la brecha cambiaria y los menores incentivos en comparaci\u00f3n a la Serie 1 y 2. Como respuesta, se estableci\u00f3 que las pr\u00f3ximas licitaciones estar\u00e1n abiertas para aquellos importadores de bienes y servicios con deudas hasta el 12 diciembre de 2023, sin necesidad de estar inscriptos en el Padr\u00f3n. Con estos n\u00fameros, la Serie 3 acumula VN USD 792 M sobre los VN USD 3.000 M que se tiene como objetivo, mientras que el stock total de BOPREALES asciende a VN USD 7.792 M en su camino a la normalizaci\u00f3n de la deuda comercial acumulada (ser\u00edan necesarios USD 13.600 M seg\u00fan estimaciones oficiales). Sin embargo, un punto no menor es que entre diciembre y enero el pago de importaciones de bienes represent\u00f3 tan s\u00f3lo el 20% de las importaciones devengadas, lo cual implica que la deuda comercial por nuevas importaciones ascendi\u00f3 a USD 7.000 M.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-16489 size-full\" src=\"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/MULC-diario-y-brecha-6.png\" alt=\"\" width=\"1600\" height=\"900\" \/><\/p>\n<p><strong>\u00bfCu\u00e1l es el principal riesgo en este contexto?<\/strong> El despertar de la brecha cambiaria generado tanto por la oferta como por la demanda. Por un lado, las pr\u00e1cticamente nulas opciones de inversi\u00f3n para resguardarse frente a los mayores niveles de nominalidad, junto con la vigencia de una tasa de inter\u00e9s sumamente negativa en t\u00e9rminos reales quitan incentivos a ahorrar en pesos. Por ende, un stock de pesos que se encuentra expectante podr\u00eda <strong>redireccionarse hacia los d\u00f3lares alternativos<\/strong>, generando as\u00ed una mayor demanda de USD por fuera del MULC.<\/p>\n<p>Paralelamente, si bien <strong>los exportadores tienen incentivos a liquidar<\/strong> frente a la continua ca\u00edda en los precios internacionales y el elevado spread entre la tasa de inter\u00e9s y el crawling peg (tasa en 8% mensual contra una devaluaci\u00f3n mensual del 2%), el esquema se considerar\u00e1 sostenible siempre y cuando los tenedores de los USD no perciban que puede ocurrir un nuevo salto discreto del TC oficial en el corto plazo.<\/p>\n<p>El ingreso de divisas proveniente de la cosecha gruesa es fundamental para mantener el saldo comprador del BCRA frente a una demanda que paulatinamente se ir\u00e1 incrementando producto del esquema de acceso escalonado. A su vez, una menor liquidaci\u00f3n de exportaciones reducir\u00eda tambi\u00e9n la oferta de USD en los mercados financieros, <strong>sumando presiones a la brecha cambiaria. <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3>Se incrementan las compras del BCRA<\/h3>\n<p><strong>El BCRA aceler\u00f3 el ritmo de compras en el MULC.<\/strong> En n\u00fameros, la autoridad monetaria adquiri\u00f3 m\u00e1s de USD 1.000 M en las \u00faltimas 5 ruedas, promediando compras diarias por poco m\u00e1s de USD 200 M (marcada mejora contra el promedio de USD 50 M en la semana previa). De esta manera, las compras netas sumar\u00edan m\u00e1s de USD 9.600 M desde el cambio de mandato. Como consecuencia, las Reservas Netas (considerando los DEG pero excluyendo el resto de los pasivos del BCRA) muestran una mejora de USD 8.000 M desde el 7\/12, pero a\u00fan contin\u00faan en terreno negativo por USD 3.000 M.<\/p>\n<h3>La brecha cambiaria contin\u00faa en niveles bajos<\/h3>\n<p><strong>La brecha cambiaria hil\u00f3 su s\u00e9ptima semana consecutiva a la baja<\/strong>. Puntualmente, mientras el blue ($995) mostr\u00f3 una ca\u00edda semanal de 5,2%, el MEP ($998) se redujo un 3,9% y el CCL v\u00eda CEDEAR ($1.047) cay\u00f3 tambi\u00e9n un 3,9%. Si bien dicha reducci\u00f3n podr\u00eda explicarse en parte por una menor demanda (producto de la reducci\u00f3n real del stock de pesos y la din\u00e1mica recesiva), sostenemos que el principal motivo ser\u00eda una mayor oferta de divisas proveniente de las liquidaciones por exportaciones que se negocian al CCL (esquema 80%-20%). En consecuencia, la brecha cambiaria promedio cerr\u00f3 la semana en 19,7%, 6 p.p. por debajo del viernes previo.<\/p>\n<h3>Marcado recorte en futuros del d\u00f3lar<\/h3>\n<p>Marcado recorte en futuros del d\u00f3lar. Luego del rebote evidenciado el \u00faltimo viernes en la previa al discurso presidencial, los contratos a futuros del d\u00f3lar evidenciaron fuertes ca\u00eddas en la \u00faltima semana. Puntualmente, los TC impl\u00edcitos en los contratos con vencimiento entre marzo y mayo (los m\u00e1s relevante en cuanto al volumen) mostraron bajas semanales que promediaron el 6%, reflejando una devaluaci\u00f3n esperada para marzo que pas\u00f3 del 10,3% a apenas 3,2%.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3525,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Bruno Bonfanti","image_url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/Fondo-cambiario.jpeg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una semana con reacciones positivas - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-08T22:35:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-08T22:35:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una semana con reacciones positivas - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#blogposting\",\"name\":\"Una semana con reacciones positivas - Ecolatina\",\"headline\":\"Una semana con reacciones positivas\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-1.jpeg\",\"width\":1280,\"height\":842},\"datePublished\":\"2024-03-08T19:35:28-03:00\",\"dateModified\":\"2024-03-08T19:35:28-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#listItem\",\"name\":\"Una semana con reacciones positivas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#listItem\",\"position\":3,\"name\":\"Una semana con reacciones positivas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/\",\"name\":\"Una semana con reacciones positivas - Ecolatina\",\"description\":\"En el marco de una reacci\\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \\u00faltima semana. Sin embargo, a\\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-1.jpeg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#mainImage\",\"width\":1280,\"height\":842},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#mainImage\"},\"datePublished\":\"2024-03-08T19:35:28-03:00\",\"dateModified\":\"2024-03-08T19:35:28-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Una semana con reacciones positivas - Ecolatina","description":"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha","canonical_url":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#blogposting","name":"Una semana con reacciones positivas - Ecolatina","headline":"Una semana con reacciones positivas","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-1.jpeg","width":1280,"height":842},"datePublished":"2024-03-08T19:35:28-03:00","dateModified":"2024-03-08T19:35:28-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#listItem","name":"Una semana con reacciones positivas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#listItem","position":3,"name":"Una semana con reacciones positivas","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#webpage","url":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","name":"Una semana con reacciones positivas - Ecolatina","description":"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-1.jpeg","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#mainImage","width":1280,"height":842},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#mainImage"},"datePublished":"2024-03-08T19:35:28-03:00","dateModified":"2024-03-08T19:35:28-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Una semana con reacciones positivas - Ecolatina","og:description":"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha","og:url":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","article:published_time":"2024-03-08T22:35:28+00:00","article:modified_time":"2024-03-08T22:35:28+00:00","twitter:card":"summary_large_image","twitter:title":"Una semana con reacciones positivas - Ecolatina","twitter:description":"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. En resumen: 1) La brecha"},"aioseo_meta_data":{"post_id":"3524","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-08 22:51:21","updated":"2025-06-04 01:50:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUna semana con reacciones positivas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Una semana con reacciones positivas","link":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una semana con reacciones positivas - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una semana con reacciones positivas - Ecolatina\" \/>\n<meta property=\"og:description\" content=\"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T22:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/MULC-diario-y-brecha-6.png\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Una semana con reacciones positivas\",\"datePublished\":\"2024-03-08T22:35:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/\"},\"wordCount\":1420,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-1.jpeg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/\",\"name\":\"Una semana con reacciones positivas - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-1.jpeg\",\"datePublished\":\"2024-03-08T22:35:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-1.jpeg\",\"width\":1280,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/08\\\/una-semana-con-reacciones-positivas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una semana con reacciones positivas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una semana con reacciones positivas - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","og_locale":"en_US","og_type":"article","og_title":"Una semana con reacciones positivas - Ecolatina","og_description":"En el marco de una reacci\u00f3n positiva de los mercados al discurso de Javier Milei en la apertura de sesiones ordinarias del Congreso, el Gobierno continu\u00f3 avanzando en su estrategia cambiaria-monetaria durante la \u00faltima semana. Sin embargo, a\u00fan persisten ciertos riesgos latentes que pueden poner en jaque el esquema vigente. [&hellip;]","og_url":"https:\/\/ecolatina.com\/en\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","og_site_name":"Ecolatina","article_published_time":"2024-03-08T22:35:28+00:00","og_image":[{"url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/MULC-diario-y-brecha-6.png","type":"","width":"","height":""}],"author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Una semana con reacciones positivas","datePublished":"2024-03-08T22:35:28+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/"},"wordCount":1420,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-1.jpeg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","url":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/","name":"Una semana con reacciones positivas - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-1.jpeg","datePublished":"2024-03-08T22:35:28+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-1.jpeg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-1.jpeg","width":1280,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2024\/03\/08\/una-semana-con-reacciones-positivas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Una semana con reacciones positivas"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=3524"}],"version-history":[{"count":0,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/3525"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=3524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=3524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=3524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}