{"id":3537,"date":"2024-03-22T20:16:26","date_gmt":"2024-03-22T23:16:26","guid":{"rendered":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/"},"modified":"2024-03-22T20:16:26","modified_gmt":"2024-03-22T23:16:26","slug":"camino-a-la-cosecha-gruesa","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","title":{"rendered":"Camino a la cosecha gruesa"},"content":{"rendered":"<p><em>En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente estables; y 4) El Tesoro alcanz\u00f3 nuevamente un resultado positivo en la licitaci\u00f3n de la semana. Como aspecto negativo, la demanda de la Serie 3 del BOPREAL no levanta.<\/em><\/p>\n<p><em>\u00bfCu\u00e1les fueron las novedades en la licitaci\u00f3n del Tesoro? a) Se anunci\u00f3 que parte de la liquidez extra estar\u00e1 dirigida a la compra de divisas al BCRA que se destinar\u00e1n a pagar los vencimientos por Globales y Bonares en julio; y b) Volvieron a colocarse LECAP: letras que pagan una tasa efectiva mensual capitalizable mensualmente (5,5% en este caso) y que no se utilizaban desde 2019. \u00bfCu\u00e1l es la ventaja? Por un lado, se desindexa el perfil de vencimientos en pesos del Tesoro. A su vez, si bien las letras devengan intereses, estos no impactan en caja hasta su vencimiento (enero del 2025), lo cual juega a favor del equilibrio financiero en 2024.<\/em><\/p>\n<p><em>M\u00e1s all\u00e1 de los interrogantes sobre la sostenibilidad y el horizonte de la estrategia, el esquema actual depende principalmente de 2 elementos: la vigencia del CEPO y las expectativas de devaluaci\u00f3n. En cuanto al segundo elemento, la din\u00e1mica de la brecha cambiaria (uno de los principales term\u00f3metros) se rige m\u00e1s por flujos que por fundamentos macroecon\u00f3micos o novedades pol\u00edtico-legislativas. Por tal motivo, ser\u00e1 clave monitorear la liquidaci\u00f3n de la cosecha gruesa en los pr\u00f3ximos meses: no s\u00f3lo definir\u00e1 la capacidad de recuperaci\u00f3n de las Reservas Internacionales, sino tambi\u00e9n la estabilidad de la brecha cambiaria.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su <strong>audaz estrategia cambiaria-monetaria: 1)<\/strong> El BCRA continu\u00f3 comprando divisas en el MULC; <strong>2)<\/strong> La brecha cambiaria se mantuvo en niveles bajos; <strong>3)<\/strong> Los futuros del d\u00f3lar se mantuvieron relativamente estables; y <strong>4)<\/strong> El Tesoro alcanz\u00f3 nuevamente un resultado positivo en la licitaci\u00f3n de la semana. Como aspecto negativo, la demanda de la Serie 3 del BOPREAL no levanta.<\/p>\n<p>Con respecto al Tesoro, las autoridades lograron<strong> captar un financiamiento por $1,32 billones sobre vencimientos por $541.000 M<\/strong>, cifra que implica un <em>rollover <\/em>de 245%. <strong>\u00bfLas novedades?<\/strong> <strong>a)<\/strong> Se anunci\u00f3 que parte de la liquidez extra estar\u00e1 dirigida a la compra de divisas al BCRA que se destinar\u00e1n a pagar los vencimientos por Globales y Bonares en julio; y <strong>b)<\/strong> Volvieron a colocarse LECAP: letras que pagan una tasa efectiva mensual capitalizable mensualmente (5,5% en este caso) y que no se utilizaban desde 2019. <strong>\u00bfCu\u00e1l es la ventaja?<\/strong> Por un lado, se desindexa el perfil de vencimientos en pesos del Tesoro. A su vez, si bien las letras devengan intereses, estos no impactan en caja hasta su vencimiento (enero del 2025), lo cual juega a favor del equilibrio financiero en 2024.<\/p>\n<p>En este contexto, <strong>el<\/strong> <strong>BCRA continu\u00f3 saneando su hoja de balance<\/strong>. La baja de tasas instrumentadas la semana previa le quit\u00f3 atractivo (al menos inicialmente) a los Pases, despejando as\u00ed el camino para que la liquidez se redireccione desde pasivos del BCRA hacia instrumento del Tesoro (tanto en las licitaciones primarias como en el canje).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-16591 size-full\" src=\"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/MULC-diario-y-brecha-7.png\" alt=\"\" width=\"1600\" height=\"900\" \/><\/p>\n<p>M\u00e1s all\u00e1 de los interrogantes sobre la sostenibilidad y el horizonte de la estrategia de \u201clicuaci\u00f3n\u201d (reducci\u00f3n real) del stock de pesos frente a una tasa real extremadamente negativa, el esquema actual depende principalmente de 2 elementos: <strong>la vigencia del CEPO y las expectativas de devaluaci\u00f3n<\/strong>.<\/p>\n<p>En cuanto al segundo elemento, en las \u00faltimas semanas qued\u00f3 en evidencia que <strong>la din\u00e1mica de la brecha cambiaria en el marco del CEPO depende m\u00e1s de los flujos <\/strong>que de los fundamentos macroecon\u00f3micos o las novedades pol\u00edtico-legislativas. \u00bfA qu\u00e9 nos referimos con flujos? a) Una <strong>demanda reprimida<\/strong> por el apret\u00f3n monetario, la recesi\u00f3n y el deterioro real de los ingresos (sumado a las restricciones cruzadas MULC-CCL); y b) Una <strong>oferta elevada <\/strong>producto del 20% de las exportaciones que se direcciona hacia los USD financieros dado el esquema de d\u00f3lar <em>blend<\/em>.<\/p>\n<p>Por tal motivo, sostenemos que el \u00e9xito de la estrategia cambiaria-monetaria del Gobierno depende de la <strong>liquidaci\u00f3n de divisas proveniente de la cosecha gruesa. <\/strong>Por un lado, ser\u00e1 vital que se incremente la oferta en el MULC para empalmar una creciente demanda de divisas por importaciones (fruto del esquema escalonado del 25%). Para dimensionar, mientras en diciembre se pag\u00f3 s\u00f3lo el 17% de las importaciones devengadas, en febrero esta relaci\u00f3n subi\u00f3 al 41% y seguramente siga creciendo. A su vez, el 20% de las divisas que se liquide al CCL ser\u00e1 fundamental para dotar de oferta un mercado financiero sensible a la volatilidad en las expectativas.<\/p>\n<p>A modo de cierre, si bien las autoridades pueden ofrecer mayores incentivos a los productores para fomentar la liquidaci\u00f3n, la cuesti\u00f3n pasa por las expectativas: el esquema se considerar\u00e1 sostenible siempre y cuando los tenedores de los granos no perciban que puede ocurrir un nuevo salto discreto del TC oficial en el corto plazo. En pocas palabras, <strong>frente a una expectativa de devaluaci\u00f3n en el corto plazo, no hay incentivo que sea suficiente<\/strong>. En todo caso, bien cabe preguntarse si la decisi\u00f3n oficial de postergar los aumentos tarifarios y su consecuente impacto inflacionario fue realizada para generar <strong>expectativas de un tipo de cambio menos castigado <\/strong>camino a la gruesa.<\/p>\n<h3>El BCRA sostuvo las compras en el MULC<\/h3>\n<p>En la \u00faltima semana, <strong>el BCRA desaceler\u00f3 el ritmo de compras<\/strong>, adquiriendo USD 505 M (vs USD 1.018 M la semana previa), producto de una oferta que registr\u00f3 una leve reducci\u00f3n y una demanda que se mantuvo estable. Como consecuencia, las Reservas Netas (considerando los DEG pero excluyendo el resto de los pasivos del BCRA) muestran una mejor cercana a USD 9.000 M desde el 7\/12, pero a\u00fan contin\u00faan en terreno negativo por USD 2.100 M. Por otro lado, el BCRA logr\u00f3 colocar s\u00f3lo VN USD 89 M en la tercera licitaci\u00f3n de la Serie 3 del BOPREAL, siendo la menor colocaci\u00f3n de las cuatro subastas realizadas hasta el momento.<\/p>\n<h3>La brecha cambiaria se mantiene estable<\/h3>\n<p><strong>La brecha cambiaria sigui\u00f3 estable en niveles bajos<\/strong>. En n\u00fameros, el d\u00f3lar blue ($1.020) se redujo un 0,5% semanal, mientras que el MEP y el CCL v\u00eda CEDEAR mostraron aumentos en torno al 2%. En consecuencia, la brecha cambiaria promedio cerr\u00f3 la semana en 22,6%, 0,8p.p. por encima del viernes previo. Al igual que las \u00faltimas semanas, sostenemos que la din\u00e1mica de los USD alternativos se explica tanto por una demanda reprimida como por una elevada oferta producto del esquema 80%-20%.<\/p>\n<h3>Relativa estabilidad en futuros del d\u00f3lar<\/h3>\n<p><strong>Los contratos a futuros del d\u00f3lar se mantuvieron relativamente estables durante la \u00faltima semana<\/strong>. Puntualmente, los TC impl\u00edcitos en los contratos con vencimiento entre marzo y mayo (los m\u00e1s relevante en cuanto al volumen) mostraron bajas semanales que promediaron el 0,3%, mientras que los contratos con vencimiento de junio en adelante promediaron ca\u00eddas del 0,6% semanal. Si bien la devaluaci\u00f3n esperada para marzo se acerca al 2% pautado por el Gobierno, desde el contrato de abril la variaci\u00f3n esperada se sit\u00faa por encima del 6% mensual.<\/p>","protected":false},"excerpt":{"rendered":"<p>En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3538,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Kevin Pagnotta","image_url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/Fondo-cambiario.jpeg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Camino a la cosecha gruesa - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-22T23:16:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-22T23:16:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Camino a la cosecha gruesa - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#blogposting\",\"name\":\"Camino a la cosecha gruesa - Ecolatina\",\"headline\":\"Camino a la cosecha gruesa\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-3.jpeg\",\"width\":1280,\"height\":842},\"datePublished\":\"2024-03-22T20:16:26-03:00\",\"dateModified\":\"2024-03-22T20:16:26-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#listItem\",\"name\":\"Camino a la cosecha gruesa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#listItem\",\"position\":3,\"name\":\"Camino a la cosecha gruesa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/\",\"name\":\"Camino a la cosecha gruesa - Ecolatina\",\"description\":\"En medio de una reacci\\u00f3n positiva de los mercados financieros que se extendi\\u00f3 a lo largo de toda la semana, el Gobierno continu\\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\\u00f3lar se mantuvieron relativamente\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-3.jpeg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#mainImage\",\"width\":1280,\"height\":842},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#mainImage\"},\"datePublished\":\"2024-03-22T20:16:26-03:00\",\"dateModified\":\"2024-03-22T20:16:26-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Camino a la cosecha gruesa - Ecolatina","description":"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente","canonical_url":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#blogposting","name":"Camino a la cosecha gruesa - Ecolatina","headline":"Camino a la cosecha gruesa","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-3.jpeg","width":1280,"height":842},"datePublished":"2024-03-22T20:16:26-03:00","dateModified":"2024-03-22T20:16:26-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#listItem","name":"Camino a la cosecha gruesa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#listItem","position":3,"name":"Camino a la cosecha gruesa","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#webpage","url":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","name":"Camino a la cosecha gruesa - Ecolatina","description":"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-3.jpeg","@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#mainImage","width":1280,"height":842},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#mainImage"},"datePublished":"2024-03-22T20:16:26-03:00","dateModified":"2024-03-22T20:16:26-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Camino a la cosecha gruesa - Ecolatina","og:description":"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente","og:url":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","article:published_time":"2024-03-22T23:16:26+00:00","article:modified_time":"2024-03-22T23:16:26+00:00","twitter:card":"summary_large_image","twitter:title":"Camino a la cosecha gruesa - Ecolatina","twitter:description":"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros del d\u00f3lar se mantuvieron relativamente"},"aioseo_meta_data":{"post_id":"3537","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-22 23:24:21","updated":"2025-06-04 01:50:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCamino a la cosecha gruesa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Camino a la cosecha gruesa","link":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camino a la cosecha gruesa - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camino a la cosecha gruesa - Ecolatina\" \/>\n<meta property=\"og:description\" content=\"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-22T23:16:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/MULC-diario-y-brecha-7.png\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Camino a la cosecha gruesa\",\"datePublished\":\"2024-03-22T23:16:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/\"},\"wordCount\":1233,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-3.jpeg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/\",\"name\":\"Camino a la cosecha gruesa - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-3.jpeg\",\"datePublished\":\"2024-03-22T23:16:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Fondo-cambiario-3.jpeg\",\"width\":1280,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/03\\\/22\\\/camino-a-la-cosecha-gruesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camino a la cosecha gruesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camino a la cosecha gruesa - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","og_locale":"en_US","og_type":"article","og_title":"Camino a la cosecha gruesa - Ecolatina","og_description":"En medio de una reacci\u00f3n positiva de los mercados financieros que se extendi\u00f3 a lo largo de toda la semana, el Gobierno continu\u00f3 avanzando en su audaz estrategia cambiaria-monetaria: 1) El BCRA continu\u00f3 comprando divisas en el MULC; 2) La brecha cambiaria se mantuvo en niveles bajos; 3) Los futuros [&hellip;]","og_url":"https:\/\/ecolatina.com\/en\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","og_site_name":"Ecolatina","article_published_time":"2024-03-22T23:16:26+00:00","og_image":[{"url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/MULC-diario-y-brecha-7.png","type":"","width":"","height":""}],"author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Camino a la cosecha gruesa","datePublished":"2024-03-22T23:16:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/"},"wordCount":1233,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-3.jpeg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","url":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/","name":"Camino a la cosecha gruesa - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-3.jpeg","datePublished":"2024-03-22T23:16:26+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-3.jpeg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/03\/Fondo-cambiario-3.jpeg","width":1280,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2024\/03\/22\/camino-a-la-cosecha-gruesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Camino a la cosecha gruesa"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=3537"}],"version-history":[{"count":0,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/3538"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=3537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=3537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=3537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}