{"id":3615,"date":"2024-07-12T08:55:26","date_gmt":"2024-07-12T11:55:26","guid":{"rendered":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/"},"modified":"2024-07-12T08:55:26","modified_gmt":"2024-07-12T11:55:26","slug":"resumen-diario-12-07-24","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/","title":{"rendered":"Resumen Diario | 12.07.24"},"content":{"rendered":"<h3>ESCENARIO ECON\u00d3MICO<\/h3>\n<p><strong>Fin de los Pases<\/strong>. En la jornada de ayer, mediante Comunicaci\u00f3n &#8220;A&#8221; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &#8220;Letras Fiscales de Liquidez&#8221; (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por el Tesoro, con intereses capitalizables por el plazo de un a\u00f1o (devengan intereses en 2024, pero pagan en 2025) y pagar\u00e1n la tasa establecida por el BCRA. Adem\u00e1s, la autoridad monetaria estableci\u00f3 que las mismas ser\u00e1n excluidas a los l\u00edmites de financiamiento del sector p\u00fablico y, a diferencia de los Pases, no ser\u00e1n admitidas para ser integradas como encajes.<\/p>\n<p><strong>El BCRA contin\u00faa con compras<\/strong> El BCRA compr\u00f3 USD 50 M este jueves. As\u00ed la autoridad monetaria acumula compras por USD 14.487 M en lo que va del a\u00f1o y USD 17.383 M desde el inicio de la gesti\u00f3n. Como resultado, las Reservas Internacionales ascienden a USD 28.225 M.<\/p>\n<p><strong>D\u00f3lares al alza.<\/strong> Este jueves el d\u00f3lar blue cerr\u00f3 en $1.465 subiendo 1%, mientras que el d\u00f3lar MEP (AL30) avanz\u00f3 +1,6% quedando en $1.398 y el d\u00f3lar CCL (operado con CEDEARS) escal\u00f3 +1,7% hasta los $1.414. De este modo, la brecha cambiaria promedio se posiciona en 55%.<\/p>\n<p><strong>Mercado financiero local con resultados mixtos.<\/strong> En la jornada de ayer el S&amp;P Merval retrocedi\u00f3 -0,8% en d\u00f3lares, cerrando en USD 1.206. Por su parte, los Globales retrocedieron -0,2% y los Bonares subieron +0,1%. Como resultado, el riesgo pa\u00eds cerr\u00f3 en 1473 puntos b\u00e1sicos.<\/p>\n<p>LO QUE EST\u00c1 SUCEDIENDO<\/p>\n<p><strong>La inflaci\u00f3n de USA se desacelera m\u00e1s que lo esperada<\/strong>. En junio, la inflaci\u00f3n de Estados Unidos fue de -0,1% mensual, por debajo de lo que estimaba el mercado (+0,1%) y desaceler\u00e1ndose 0,1 p.p. respecto a lo observado en el mes anterior. De esta manera, se acumularon tres meses consecutivos de desaceleraci\u00f3n. El nivel general mostr\u00f3 una suba de 3,0% en t\u00e9rminos anuales, desacelerando 0,3 p.p. respecto a abril. Por su parte, la inflaci\u00f3n core -que excluye los costos de alimentos y energ\u00eda- se mantuvo no exhibi\u00f3 cambios respecto al mes anterior, siendo de 3,3% en la comparaci\u00f3n interanual.<\/p>\n<p>TEN\u00c9S QUE SABER<\/p>\n<p><strong>Cerr\u00f3 la campa\u00f1a de soja con una producci\u00f3n en l\u00ednea con el promedio<\/strong>. Seg\u00fan la Bolsa de Cereales, en la campa\u00f1a 2023\/24 la producci\u00f3n total de la oleaginosa se ubic\u00f3 en 50,5 millones de toneladas, 27,5 MTn por encima de la campa\u00f1a previa -fuertemente afectada por la sequ\u00eda-, pero en l\u00ednea con el promedio de los \u00faltimos ciclos. La entidad estima que la campa\u00f1a del complejo sojero generar\u00eda exportaciones por USD 19.868 M (+35% respecto a la campa\u00f1a previa) y USD 8.052 M por recaudaci\u00f3n fiscal (+66%).<\/p>","protected":false},"excerpt":{"rendered":"<p>ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &#8220;A&#8221; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &#8220;Letras Fiscales de Liquidez&#8221; (LEFI). Cabe recordar que estas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3616,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Ana Albin","image_url":"http:\/\/ecolatina-2018.appspot.com.storage.googleapis.com\/5.-Viernes.png","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &quot;A&quot; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &quot;Letras Fiscales de Liquidez&quot; (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Resumen Diario | 12.07.24 - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &quot;A&quot; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &quot;Letras Fiscales de Liquidez&quot; (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-12T11:55:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-12T11:55:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Resumen Diario | 12.07.24 - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &quot;A&quot; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &quot;Letras Fiscales de Liquidez&quot; (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#blogposting\",\"name\":\"Resumen Diario | 12.07.24 - Ecolatina\",\"headline\":\"Resumen Diario | 12.07.24\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/5.-Viernes.png\",\"width\":2500,\"height\":1407},\"datePublished\":\"2024-07-12T08:55:26-03:00\",\"dateModified\":\"2024-07-12T08:55:26-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#listItem\",\"name\":\"Resumen Diario | 12.07.24\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#listItem\",\"position\":3,\"name\":\"Resumen Diario | 12.07.24\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/\",\"name\":\"Resumen Diario | 12.07.24 - Ecolatina\",\"description\":\"ESCENARIO ECON\\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\\u00f3n \\\"A\\\" 8060 y 8061, el BCRA anunci\\u00f3 que dejar\\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas \\\"Letras Fiscales de Liquidez\\\" (LEFI). Cabe recordar que estas nacientes letras ser\\u00e1n emitidas por\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/5.-Viernes.png\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#mainImage\",\"width\":2500,\"height\":1407},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#mainImage\"},\"datePublished\":\"2024-07-12T08:55:26-03:00\",\"dateModified\":\"2024-07-12T08:55:26-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Resumen Diario | 12.07.24 - Ecolatina","description":"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n \"A\" 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas \"Letras Fiscales de Liquidez\" (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por","canonical_url":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#blogposting","name":"Resumen Diario | 12.07.24 - Ecolatina","headline":"Resumen Diario | 12.07.24","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/07\/5.-Viernes.png","width":2500,"height":1407},"datePublished":"2024-07-12T08:55:26-03:00","dateModified":"2024-07-12T08:55:26-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#listItem","name":"Resumen Diario | 12.07.24"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#listItem","position":3,"name":"Resumen Diario | 12.07.24","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#webpage","url":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/","name":"Resumen Diario | 12.07.24 - Ecolatina","description":"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n \"A\" 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas \"Letras Fiscales de Liquidez\" (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/07\/5.-Viernes.png","@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#mainImage","width":2500,"height":1407},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/#mainImage"},"datePublished":"2024-07-12T08:55:26-03:00","dateModified":"2024-07-12T08:55:26-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Resumen Diario | 12.07.24 - Ecolatina","og:description":"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &quot;A&quot; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &quot;Letras Fiscales de Liquidez&quot; (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por","og:url":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/","article:published_time":"2024-07-12T11:55:26+00:00","article:modified_time":"2024-07-12T11:55:26+00:00","twitter:card":"summary_large_image","twitter:title":"Resumen Diario | 12.07.24 - Ecolatina","twitter:description":"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &quot;A&quot; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &quot;Letras Fiscales de Liquidez&quot; (LEFI). Cabe recordar que estas nacientes letras ser\u00e1n emitidas por"},"aioseo_meta_data":{"post_id":"3615","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-07-12 12:03:22","updated":"2025-06-04 01:52:01","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tResumen Diario | 12.07.24\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Resumen Diario | 12.07.24","link":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resumen Diario | 12.07.24 - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumen Diario | 12.07.24 - Ecolatina\" \/>\n<meta property=\"og:description\" content=\"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &#8220;A&#8221; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &#8220;Letras Fiscales de Liquidez&#8221; (LEFI). Cabe recordar que estas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T11:55:26+00:00\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Resumen Diario | 12.07.24\",\"datePublished\":\"2024-07-12T11:55:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/\"},\"wordCount\":465,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/5.-Viernes.png\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/\",\"name\":\"Resumen Diario | 12.07.24 - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/5.-Viernes.png\",\"datePublished\":\"2024-07-12T11:55:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/5.-Viernes.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/5.-Viernes.png\",\"width\":2500,\"height\":1407},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2024\\\/07\\\/12\\\/resumen-diario-12-07-24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumen Diario | 12.07.24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resumen Diario | 12.07.24 - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/","og_locale":"en_US","og_type":"article","og_title":"Resumen Diario | 12.07.24 - Ecolatina","og_description":"ESCENARIO ECON\u00d3MICO Fin de los Pases. En la jornada de ayer, mediante Comunicaci\u00f3n &#8220;A&#8221; 8060 y 8061, el BCRA anunci\u00f3 que dejar\u00e1 de ofrecer Pases a las entidades bancarias a partir del 22 de julio, ofreciendo en su lugar las nuevas &#8220;Letras Fiscales de Liquidez&#8221; (LEFI). Cabe recordar que estas [&hellip;]","og_url":"https:\/\/ecolatina.com\/en\/2024\/07\/12\/resumen-diario-12-07-24\/","og_site_name":"Ecolatina","article_published_time":"2024-07-12T11:55:26+00:00","author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Resumen Diario | 12.07.24","datePublished":"2024-07-12T11:55:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/"},"wordCount":465,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/07\/5.-Viernes.png","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/","url":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/","name":"Resumen Diario | 12.07.24 - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/07\/5.-Viernes.png","datePublished":"2024-07-12T11:55:26+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/07\/5.-Viernes.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2024\/07\/5.-Viernes.png","width":2500,"height":1407},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2024\/07\/12\/resumen-diario-12-07-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Resumen Diario | 12.07.24"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=3615"}],"version-history":[{"count":0,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/3616"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=3615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=3615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=3615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}