{"id":3889,"date":"2025-01-13T12:27:00","date_gmt":"2025-01-13T15:27:00","guid":{"rendered":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/"},"modified":"2025-01-13T12:27:00","modified_gmt":"2025-01-13T15:27:00","slug":"se-sostienen-las-compras-pero-caen-las-reservas","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","title":{"rendered":"Se sostienen las compras, pero caen las Reservas"},"content":{"rendered":"<p><span style=\"color: #000000;\"><em>El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el BCRA logr\u00f3 retomar las compras de divisas en las primeras ruedas del a\u00f1o. M\u00e1s all\u00e1 del buen desempe\u00f1o de la autoridad monetaria en el MULC, las novedades de la semana pasaron por: 1) El impacto de los pagos de deuda en USD del Tesoro; 2) La posibilidad de una eventual reducci\u00f3n del crawling peg al 1% (e incluso una baja de tasas) en las pr\u00f3ximas ruedas luego de conocer el dato de inflaci\u00f3n de diciembre; y 3) La reaparici\u00f3n de la volatilidad internacional, principalmente en USA y Brasil.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><em>En las \u00faltimas 8 ruedas el BCRA acumul\u00f3 compras por USD 908 M gracias al dinamismo de los pr\u00e9stamos en USD, una liquidaci\u00f3n del agro que se sostuvo en niveles elevados y una demanda que se mantuvo relativamente acotada. Pese a la racha positiva del BCRA en el MULC, las Reservas Internacionales cayeron USD 1.865 M en las \u00faltimas 3 ruedas producto de los pagos de deuda en USD del Tesoro. <\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><em>Otro de los datos comentados durante la semana fue la posibilidad de una reducci\u00f3n en el ritmo del crawling peg. Pese a que fue de gran ayuda en el proceso de desaceleraci\u00f3n inflacionaria, con la reducci\u00f3n de la nominalidad est\u00e1 dejando de actuar como un ancla para pasar a comportarse como un componente inercial. En este sentido, dif\u00edcilmente la inflaci\u00f3n logre perforar el pr\u00f3ximo piso inercial sin una moderaci\u00f3n de la pauta de devaluaci\u00f3n oficial.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><em>\u00a0<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">El arranque de a\u00f1o para el Gobierno continu\u00f3 con una <strong>relativa estabilidad en materia cambiaria-financiera:<\/strong> no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el BCRA logr\u00f3 retomar las compras de divisas en las primeras ruedas del a\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">M\u00e1s all\u00e1 del buen desempe\u00f1o de la autoridad monetaria en el MULC, las novedades de la semana pasaron por: <strong>1)<\/strong> El impacto de los pagos de deuda en USD del Tesoro; <strong>2)<\/strong> La posibilidad de una eventual reducci\u00f3n del crawling peg al 1% (e incluso una baja de tasas) en las pr\u00f3ximas ruedas luego de conocer el dato de inflaci\u00f3n de diciembre; y <strong>3)<\/strong> La reaparici\u00f3n de la volatilidad internacional, principalmente en USA y Brasil.<\/span><\/p>\n<p><span style=\"color: #000000;\">En las \u00faltimas 8 ruedas <strong>el BCRA acumul\u00f3 compras<\/strong> por USD 908 M gracias al dinamismo de los pr\u00e9stamos en USD, una liquidaci\u00f3n del agro que se sostuvo en niveles elevados y una demanda que se mantuvo relativamente acotada. Pese a la racha positiva del BCRA en el MULC, las Reservas Internacionales cayeron USD 1.865 M en las \u00faltimas 3 ruedas producto de los <strong>pagos de deuda en USD del Tesoro<\/strong>. En n\u00fameros, si bien las autoridades deb\u00edan afrontar vencimientos de capital e intereses por cerca de USD 4.400 M el 9 de enero, una parte ya hab\u00eda sido girada al Banco de Nuevo York durante octubre, dejando un pendiente de USD 3.400 M por cancelar.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por tal motivo, las <strong>Reservas L\u00edquidas<\/strong> (tienen en cuenta los activos l\u00edquidos en USD con los que cuenta el BCRA para intervenir) y las <strong>Reservas Netas<\/strong> (a los activos en USD del BCRA se les resta los pasivos de corto plazo) que no restan los dep\u00f3sitos del Tesoro habr\u00eda sufrido una marcada ca\u00edda en las \u00faltimas ruedas: pasaron de USD 15.000 M a USD 13.000 M y de -USD 3.200 M a -USD 6.000 M, respectivamente. Por el contrario, las Reservas Netas que descuentan los <strong>dep\u00f3sitos del Tesoro<\/strong> no habr\u00edan sufrido variaciones considerables, dado que el pago se afront\u00f3 con los propios USD del fisco (reduce tanto el activo como el pasivo del BCRA considerados bajo esta metodolog\u00eda).<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-18585\" src=\"http:\/\/eco-latina.com.ar\/wp-content\/uploads\/2025\/01\/MULC-diario-y-Reservas-Netas-VF.png\" alt=\"\" width=\"1280\" height=\"720\" \/><\/p>\n<p><span style=\"color: #000000;\">Hacia adelante, el pr\u00f3ximo vencimiento elevado de bonos soberanos en USD ser\u00eda a principios de julio, cuando el Tesoro deber\u00e1 cancelar compromisos nuevamente por cerca USD 4.400 M al contabilizar tanto capital como intereses. Sin embargo, estimamos que luego del pago reciente el fisco a\u00fan contar\u00eda con USD 3.000 M depositados en su cuenta en el BCRA. Si la situaci\u00f3n cambiaria-financiera contin\u00faa relativamente estable hasta aquella fecha, la liquidez en USD disponible y la posibilidad de negociar un nuevo REPO con bancos deber\u00edan permitirle al Tesoro afrontar los pr\u00f3ximos vencimientos sin mayores inconvenientes. De todas formas, tampoco descartamos que las autoridades busquen rollear o canjear dicha deuda en alg\u00fan momento del a\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Otro de los datos comentados durante la semana fue la <strong>posibilidad de una reducci\u00f3n en el ritmo del crawling peg.<\/strong> Pese a que fue de gran ayuda en el proceso de desaceleraci\u00f3n inflacionaria, con la reducci\u00f3n de la nominalidad est\u00e1 dejando de actuar como un ancla para pasar a comportarse como un componente inercial. En este sentido, dif\u00edcilmente la inflaci\u00f3n logre perforar el pr\u00f3ximo piso inercial sin una moderaci\u00f3n de la pauta de devaluaci\u00f3n oficial.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por tal motivo, las autoridades adelantaron que si el dato de inflaci\u00f3n correspondiente a diciembre (se publica el pr\u00f3ximo martes) se ubica en torno a un 2,5%, proceder\u00e1n a reducir el ritmo del crawling peg. Si bien la inflaci\u00f3n podr\u00eda ubicarse levemente por encima, la decisi\u00f3n no dejar\u00e1 de ser pol\u00edtica, por lo que depender\u00e1 de la lectura que realicen el Ejecutivo y el equipo econ\u00f3mico de los datos. Los riesgos de la adopci\u00f3n de esta estrategia se centran en la <strong>din\u00e1mica del tipo de cambio real<\/strong>, dado que actualmente se ubica en los niveles m\u00e1s bajos de la serie y ampliar la diferencia entre la inflaci\u00f3n y el ritmo de la devaluaci\u00f3n profundizar\u00eda a\u00fan m\u00e1s la situaci\u00f3n en el marco de un contexto internacional poco amable para pa\u00edses emergentes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ahora bien, la reducci\u00f3n del crawling peg tendr\u00eda como aspecto positivo el <strong>robustecimiento de la estrategia de \u201ccarry trade\u201d local<\/strong>, uno de los pilares detr\u00e1s de las compras del BCRA en el MULC durante los \u00faltimos meses: mientras los importadores postergan pagos (reduce la demanda en el MULC) aprovechando la liquidez excedente para generar rendimiento, los exportadores aceleran las liquidaciones y optan por financiarse en USD (eleva la oferta en el MULC). De hecho, si las autoridades optan por reducir el crawling peg al 1% mensual y la situaci\u00f3n financiera se sostiene, el BCRA podr\u00eda incluso bajar la tasa de inter\u00e9s (ya aparecieron rumores de mercado), fomentando a\u00fan m\u00e1s el cr\u00e9dito y sosteniendo un diferencial positivo contra el ritmo de devaluaci\u00f3n. Claramente, m\u00e1s all\u00e1 de aquel diferencial, la clave para sostener la din\u00e1mica del proceso actual consiste en contener las expectativas de devaluaci\u00f3n. Para ello, resulta primordial mantener estable la brecha cambiaria.<\/span><\/p>\n<p><span style=\"color: #000000;\">En <strong>materia internacional<\/strong>, se public\u00f3 un dato positivo de empleo en Estados Unidos con repercusiones financieras a nivel global. Durante diciembre, el empleo en Estados Unidos registr\u00f3 un incremento por encima de las expectativas de mercado: se crearon 256 mil n\u00f3minas no agr\u00edcolas, casi 100 mil puestos m\u00e1s de los esperados para el \u00faltimo mes del a\u00f1o. Con un desempleo a la baja (0,1 pp menos que en noviembre), la FED contar\u00eda con mayor espacio para sostener durante m\u00e1s tiempo la tasa de referencia en niveles elevados (\u201chigher for longer\u201d). Como consecuencia, los rendimientos de los bonos estadounidenses subieron con fuerza a lo largo de toda la curva y se fortaleci\u00f3 el d\u00f3lar, empeorando la perspectiva para los mercados emergentes. Paralelamente, la inflaci\u00f3n sorprendi\u00f3 al alza en Brasil tras conocerse el dato de diciembre y se volvi\u00f3 a disparar el Real, lo cual redunda en una mayor apreciaci\u00f3n real para Argentina con respecto a nuestro principal socio comercial.<\/span><\/p>\n<h2><span style=\"color: #000000;\"><strong>El BCRA sostiene las compras en el MULC<\/strong><\/span><\/h2>\n<p><span style=\"color: #000000;\">Durante las \u00faltimas 5 ruedas <strong>el BCRA compr\u00f3 USD 678 M en el MULC<\/strong> producto del dinamismo de los pr\u00e9stamos en USD, una liquidaci\u00f3n del agro que se sostuvo en niveles elevados y una demanda que se mantuvo relativamente acotada. De esta manera, en lo que va del a\u00f1o la autoridad monetaria acumul\u00f3 compras por USD 908 M. Pese al saldo positivo en el MULC, las Reservas Internacionales sufrieron una ca\u00edda de USD 1.865 M en las \u00faltimas 3 ruedas producto de los pagos de deuda del Tesoro.<\/span><\/p>\n<h2><span style=\"color: #000000;\"><strong>La brecha se mantiene relativamente estable<\/strong><\/span><\/h2>\n<p><span style=\"color: #000000;\">Durante la \u00faltima semana<strong>, los d\u00f3lares alternativos continuaron mostrando cierta estabilidad<\/strong>, aunque con un leve sesgo al alza. En concreto, el d\u00f3lar blue subi\u00f3 un 0,8% semanal ($1.225), mientras que el d\u00f3lar MEP y el CCL avanzaron un 0,3% ($1.164 y $1.190 respectivamente). Como resultado, la brecha cambiaria promedio no sufri\u00f3 variaciones significativas y termin\u00f3 la semana en la zona del 15%.<\/span><\/p>\n<h2><span style=\"color: #000000;\"><strong>Futuros del d\u00f3lar levemente a la baja<\/strong><\/span><\/h2>\n<p><span style=\"color: #000000;\"><strong>Los contratos a futuro del d\u00f3lar terminaron la semana levemente a la baja.<\/strong> Puntualmente, los TC impl\u00edcitos en los contratos con vencimiento entre enero y marzo (los m\u00e1s relevantes en cuanto al volumen) evidenciaron reducciones del 0,4% en promedio durante la \u00faltima semana, mientras que de abril en adelante el ajuste promedi\u00f3 -1,1%. De esta forma, las expectativas de devaluaci\u00f3n ceden en el margen dando cuenta de la posibilidad de una reducci\u00f3n del crawling peg en el corto plazo. Sin embargo, las devaluaciones impl\u00edcitas a\u00fan se ubican por encima del 1% mensual.<\/span><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3890,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Ana Albin","image_url":"http:\/\/eco-latina.com.ar\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Se sostienen las compras, pero caen las Reservas - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-13T15:27:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-13T15:27:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Se sostienen las compras, pero caen las Reservas - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#blogposting\",\"name\":\"Se sostienen las compras, pero caen las Reservas - Ecolatina\",\"headline\":\"Se sostienen las compras, pero caen las Reservas\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Fondo-cambiario-1.jpeg\",\"width\":1280,\"height\":842},\"datePublished\":\"2025-01-13T12:27:00-03:00\",\"dateModified\":\"2025-01-13T12:27:00-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#listItem\",\"name\":\"Se sostienen las compras, pero caen las Reservas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#listItem\",\"position\":3,\"name\":\"Se sostienen las compras, pero caen las Reservas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/\",\"name\":\"Se sostienen las compras, pero caen las Reservas - Ecolatina\",\"description\":\"El arranque de a\\u00f1o para el Gobierno continu\\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\\u00eds (debajo de los 600 puntos b\\u00e1sicos, marcando m\\u00ednimos desde 2018) y los contratos a futuro de d\\u00f3lar contin\\u00faan relativamente estables (e incluso a la baja), sino que el\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Fondo-cambiario-1.jpeg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#mainImage\",\"width\":1280,\"height\":842},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#mainImage\"},\"datePublished\":\"2025-01-13T12:27:00-03:00\",\"dateModified\":\"2025-01-13T12:27:00-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Se sostienen las compras, pero caen las Reservas - Ecolatina","description":"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el","canonical_url":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#blogposting","name":"Se sostienen las compras, pero caen las Reservas - Ecolatina","headline":"Se sostienen las compras, pero caen las Reservas","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","width":1280,"height":842},"datePublished":"2025-01-13T12:27:00-03:00","dateModified":"2025-01-13T12:27:00-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#listItem","name":"Se sostienen las compras, pero caen las Reservas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#listItem","position":3,"name":"Se sostienen las compras, pero caen las Reservas","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#webpage","url":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","name":"Se sostienen las compras, pero caen las Reservas - Ecolatina","description":"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#mainImage","width":1280,"height":842},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#mainImage"},"datePublished":"2025-01-13T12:27:00-03:00","dateModified":"2025-01-13T12:27:00-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Se sostienen las compras, pero caen las Reservas - Ecolatina","og:description":"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el","og:url":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","article:published_time":"2025-01-13T15:27:00+00:00","article:modified_time":"2025-01-13T15:27:00+00:00","twitter:card":"summary_large_image","twitter:title":"Se sostienen las compras, pero caen las Reservas - Ecolatina","twitter:description":"El arranque de a\u00f1o para el Gobierno continu\u00f3 con una relativa estabilidad en materia cambiaria-financiera: no s\u00f3lo la brecha cambiaria (en torno al 15%), el Riesgo pa\u00eds (debajo de los 600 puntos b\u00e1sicos, marcando m\u00ednimos desde 2018) y los contratos a futuro de d\u00f3lar contin\u00faan relativamente estables (e incluso a la baja), sino que el"},"aioseo_meta_data":{"post_id":"3889","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-13 15:32:42","updated":"2025-06-04 01:56:47","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSe sostienen las compras, pero caen las Reservas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Se sostienen las compras, pero caen las Reservas","link":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se sostienen las compras, pero caen las Reservas - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se sostienen las compras, pero caen las Reservas - Ecolatina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-13T15:27:00+00:00\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Se sostienen las compras, pero caen las Reservas\",\"datePublished\":\"2025-01-13T15:27:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/\"},\"wordCount\":1639,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Fondo-cambiario-1.jpeg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/\",\"name\":\"Se sostienen las compras, pero caen las Reservas - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Fondo-cambiario-1.jpeg\",\"datePublished\":\"2025-01-13T15:27:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Fondo-cambiario-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Fondo-cambiario-1.jpeg\",\"width\":1280,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2025\\\/01\\\/13\\\/se-sostienen-las-compras-pero-caen-las-reservas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se sostienen las compras, pero caen las Reservas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se sostienen las compras, pero caen las Reservas - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","og_locale":"en_US","og_type":"article","og_title":"Se sostienen las compras, pero caen las Reservas - Ecolatina","og_url":"https:\/\/ecolatina.com\/en\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","og_site_name":"Ecolatina","article_published_time":"2025-01-13T15:27:00+00:00","author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Se sostienen las compras, pero caen las Reservas","datePublished":"2025-01-13T15:27:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/"},"wordCount":1639,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","url":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/","name":"Se sostienen las compras, pero caen las Reservas - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","datePublished":"2025-01-13T15:27:00+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2025\/01\/Fondo-cambiario-1.jpeg","width":1280,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2025\/01\/13\/se-sostienen-las-compras-pero-caen-las-reservas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Se sostienen las compras, pero caen las Reservas"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=3889"}],"version-history":[{"count":0,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/3889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/3890"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=3889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=3889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=3889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}