{"id":4430,"date":"2026-01-16T18:12:40","date_gmt":"2026-01-16T21:12:40","guid":{"rendered":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/"},"modified":"2026-01-16T18:12:40","modified_gmt":"2026-01-16T21:12:40","slug":"las-compras-del-bcra-no-alivian-la-escasez-de-pesos","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","title":{"rendered":"Las compras del BCRA no alivian la escasez de pesos"},"content":{"rendered":"\n<p><em>La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero, lo que situar\u00eda el techo en $1.607 en la \u00faltima rueda h\u00e1bil del segundo mes del 2026.<\/em><\/p>\n<p><em>Los \u00faltimos datos monetarios confirmaron que el pago de cupones fue compensado por el ingreso del REPO, el aumento de encajes y en menor medidas compras de d\u00f3lares del Central, lo que mantuvo inalterada las Reservas Brutas (no as\u00ed las Netas). Respecto a las compras, la contrapartida de inyecci\u00f3n de pesos luce acotada e insuficiente para un mercado con una liquidez tensada y que no fue compensada por una licitaci\u00f3n con un rollover por debajo del 100% (fue 98%). Este escenario es propicio para una volatilidad al alza de la tasa de inter\u00e9s en pesos. <\/em><\/p>\n<p><em>La paulatina monetizaci\u00f3n est\u00e1 siendo contra compra de Reservas y operaciones discrecionales en el mercado. El costo de esto es un colch\u00f3n de liquidez de los bancos privados m\u00e1s estrecho y tasas m\u00e1s sensibles al alza, con la volatilidad que presenta el esquema monetario trazado. Con lo visto hasta el momento, Finanzas est\u00e1 dejando su rol de oxigenador de liquidez en pesos en las licitaciones quincenales, para darle lugar al BCRA mediante las compras de divisas y la carta reservada de una nueva baja de encajes bancarios y su integraci\u00f3n. <\/em><\/p>\n<p>\u00a0<\/p>\n<p><strong>La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana<\/strong>. El tipo de cambio spot finaliz\u00f3 en $1.430 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). Hablando de las bandas, el dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero, lo que situar\u00eda el techo en $1.607 en la \u00faltima rueda h\u00e1bil del segundo mes del 2026, es decir, un 3,2% por encima del techo que se habr\u00eda alcanzado de continuar el r\u00e9gimen anterior de deslizamiento del 1% mensual.<\/p>\n<p>En otro orden, con los \u00faltimos datos monetarios podemos <strong>evaluar el impacto del pago de cupones de la semana anterior<\/strong>. A pesar del egreso por los vencimientos por USD 4.400 M, las Reservas Brutas se mantuvieron inalteradas en el orden de los USD 44.000 M. En estos movimientos, se encuentran tres factores compensatorios: <strong>1)<\/strong> El ingreso de USD 3.000 M por el REPO constituido por el Central con bancos privados, de los cuales el Tesoro compr\u00f3 al BCRA USD 2.319 M; <strong>2)<\/strong> El aumento de encajes bancarios por USD 1.231 M, que son contrapartida del aumento de dep\u00f3sitos en d\u00f3lares por el pago que registraron los individuos locales (el stock de dep\u00f3sitos subi\u00f3 el 9-ene +USD 675 M del sector privado y +USD 396 M del sector p\u00fablico); y <strong>3) <\/strong>En menor medida, las compras de divisas realizadas por el BCRA en el mercado.<\/p>\n<p>No obstante, <strong>las Reservas Netas pasaron a terreno negativo. <\/strong>El REPO fue por un plazo poco mayor al a\u00f1o, lo que implica que ya esta semana corresponde comenzar a descontar de la medici\u00f3n de Reservas Netas el vencimiento correspondiente a dicha operaci\u00f3n. Asimismo, recordemos que la semana pasada mencionamos que se conoci\u00f3 la cancelaci\u00f3n del tramo del Swap activado con USA por USD 2.500 M a cambio de deuda con Organismos Internacionales. Si bien se desconocen los detalles y habr\u00e1 que esperar la publicaci\u00f3n el pr\u00f3ximo 23-ene de la planilla de Reservas que informa el BCRA al FMI para echar luz sobre el tema, entendemos que por ahora corresponde tener en cuenta a la hora de calcular las RIN. En concreto, tras el pago las RIN (Brutas \u2013 Encajes \u2013 Swap \u2013 OOII \u2013 REPOs \u2013 SEDESA) pas\u00f3 del orden de los +USD 2.000 M a un rojo por -USD 1.700 M, en tanto la medici\u00f3n que adem\u00e1s descuenta los dep\u00f3sitos del Tesoro en USD y los vencimientos de BOPREAL se deterior\u00f3 desde los -USD 2.300 M hasta los -USD 4.100 M.<\/p>\n<p>Por estas razones, <strong>es una buena noticia que el Central sostenga la postura compradora en el MULC.<\/strong> La autoridad monetaria acumul\u00f3 compras por USD 469 M e hil\u00f3 dos semanas consecutivas de compras, adquiriendo s\u00f3lo el mi\u00e9rcoles USD 187 M (la compra diaria m\u00e1s elevada desde el 12\/03\/25) y hoy USD 125 M. De esta forma, desde el lunes 5 totaliza USD 687 M, lo que implica un ritmo diario de USD 69 M que de sostenerse derivar\u00eda en compras al mercado cercanas USD 1.400 M a finales de mes.<\/p>\n<p>La contrapartida de las operaciones <strong>oxigena un mercado con una liquidez en pesos tensada<\/strong>. El aumento estacional de la demanda de dinero en diciembre se plasm\u00f3 en un crecimiento de los distintos agregados monetarios, los cuales vienen estancados desde mediados de 2025. Por ejemplo, dejando a un lado el factor estacional tanto el M2 Privado (Circulante + CA), como el M3 Privado (M2 + Plazos Fijos) crecieron 1,6% mensual, cortando una racha de dos meses consecutivos a la baja. Adem\u00e1s, el cr\u00e9dito al sector privado creci\u00f3 1,1% y recuper\u00f3 parte de la ca\u00edda registrada durante noviembre. Al interior de estos, el impulso vino dado por la recuperaci\u00f3n de los pr\u00e9stamos Comerciales (+2,2% crecieron los Adelantos), pero los pr\u00e9stamos orientados al Consumo (Personales + Tarjetas), que representan cerca de la mitad del stock de pr\u00e9stamos, siguen sin levantar cabeza e hilaron cuatro meses consecutivos a la baja. Detr\u00e1s de esto, se encuentra una tasa m\u00e1s vol\u00e1til y al alza, y un deterioro de la mora de las Familias (en oct-25 se ubic\u00f3 en 7,8% de los pr\u00e9stamos, el valor m\u00e1s alto para la serie iniciada en ene-10) que deriv\u00f3 en un achicamiento de la hoja de balance de los bancos.<\/p>\n<p>Producto de esta din\u00e1mica, <strong>las entidades financieras finalizaron diciembre con una escasez de liquidez<\/strong>. A finales de 2025, la liquidez en pesos<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> descendi\u00f3 hasta ubicarse en 42,8%, cifra similar a las que se observaron durante julio y agosto del 2025, en pleno desarme de las LEFIs y volatilidad de la tasa de inter\u00e9s. Por ende, las tasas comenzaron a deslizarse al alza, llegando a negociarse cauciones a 1 d\u00eda por encima del 100% TNA en determinadas ruedas. Adem\u00e1s, la estrechez en moneda dom\u00e9stica comprimi\u00f3 el colch\u00f3n de liquidez diaria que operan los bancos con el BCRA mediante la ventanilla de Pases: la absorci\u00f3n neta de pesos del Central pas\u00f3 de un stock de $4 bn el 31\/11\/2025 a tan s\u00f3lo $0,8 bn el 30\/12\/25, e incluso se ubic\u00f3 en $0,06 bn el 14\/01\/26 (\u00faltimo dato disponible) ya en medio de las compras de divisas que realiz\u00f3 por el BCRA, que equival\u00edan a dicha fecha a una inyecci\u00f3n de pesos en el mercado por $0,7 bn ($1 bn a hoy).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-20563\" src=\"https:\/\/eco-latina.com.ar\/wp-content\/uploads\/2026\/01\/Esquema-monetario-2026.png\" alt=\"\" width=\"1280\" height=\"720\" \/><\/p>\n<p>En este contexto, <strong>Finanzas cerr\u00f3 la licitaci\u00f3n de la semana con un rollover cercano al 100% (98%)<\/strong>. La primera licitaci\u00f3n del 2026 se presentaba con el desaf\u00edo de la mencionada falta de liquidez del mercado y una reducida posici\u00f3n en pesos del Tesoro por $3,1 bn, fruto de la demanda que implic\u00f3 la compra de d\u00f3lares al Central (-$3,4 bn) que consumi\u00f3 la inyecci\u00f3n de pesos desde bancos p\u00fablicos que realiz\u00f3 Hacienda en la previa del pago de cupones (+$2,4 bn).<\/p>\n<p>Yendo al detalle, el Tesoro adjudic\u00f3 $9,37 bn frente a vencimientos por $9,59 bn. La demanda se concentr\u00f3 en instrumentos a tasa fija (69%) y, en particular, en los tramos m\u00e1s cortos de la curva, con las LECAPs m\u00e1s cercanas explicando la mayor parte de lo adjudicado. En contraste, el inter\u00e9s por los t\u00edtulos dollar linked se mantuvo bajo (2% del valor efectivo adjudicado), mientras que los instrumentos ajustables por CER representaron el 14% y la tasa variable el 15% del VEA. Asimismo, Finanzas convalid\u00f3 tasas m\u00e1s altas respecto al mercado secundario: 3,39% TEM para la S27F6, 2,86% TEM para la S29Y6, 2,51% TEM para la S30N6 y 2,58% TEM para el T30J7.<\/p>\n<p>Con todo, <strong>\u00bfqu\u00e9 nos dicen los movimientos recientes? <\/strong>Incluso d\u00e1ndole una mayor importancia a la acumulaci\u00f3n de Reservas, el Gobierno opt\u00f3 por sostener los niveles ajustados de liquidez, aunque al mismo tiempo demostr\u00f3 que de ser necesario est\u00e1 dispuesto a intervenir en el mercado (comprando LECAPs) para evitar mayor volatilidad. Mientras el Central realiza compras en el mercado (y por fuera), a la par ofrece cobertura cambiaria en el mercado secundario (dollar linked + futuros en menor medida) para incentivar la venta en el spot y absorber los pesos de la operaci\u00f3n de compras. No obstante, bien cabe mencionar que el apetito por cobertura est\u00e1 lejos de las dimensiones que alcanz\u00f3 en el contexto electoral. Por \u00faltimo, en la previa de la licitaci\u00f3n se situ\u00f3 en la curva de pesos para reducir la tasa del mercado y el costo de financiamiento que enfrent\u00f3 Finanzas.<\/p>\n<p>En suma, la paulatina <strong>monetizaci\u00f3n est\u00e1 siendo contra compra de Reservas y operaciones discrecionales en el mercado. <\/strong>El costo de esto es un colch\u00f3n de liquidez de los bancos privados m\u00e1s estrecho y tasas m\u00e1s sensibles al alza, con la volatilidad que presenta el esquema monetario trazado. Con lo visto hasta el momento, Finanzas est\u00e1 dejando su rol de oxigenador de liquidez en pesos en las licitaciones quincenales, para darle lugar al BCRA mediante las compras de divisas y la carta reservada de <strong>una nueva baja de encajes bancarios y su integraci\u00f3n<\/strong>.<\/p>\n<h3>Baja el d\u00f3lar oficial<\/h3>\n<p>El tipo de cambio spot finaliz\u00f3 en $1.430, ubic\u00e1ndose 2,4% por debajo de la cotizaci\u00f3n del viernes anterior y 8,1% por debajo del techo de la banda, la distancia m\u00e1s elevada desde el 17 de noviembre del 2025. Por otro lado, el BCRA aceler\u00f3 las compras al acumular USD 469 M en la semana y las Reservas Netas (Brutas \u2013 Swap CH y USA \u2013 Encajes \u2013 REPOs \u2013 SEDESA) se habr\u00edan ubicado en torno a los -USD 1.700 M.<\/p>\n<h3>La brecha cambiaria se estabiliza<\/h3>\n<p>Los d\u00f3lares alternativos finalizaron a la baja: el d\u00f3lar minorista baj\u00f3 2,0% ($1.483) respecto al viernes de la semana anterior, el d\u00f3lar MEP operado con AL30 cay\u00f3 1,2% ($1.467), el CCL operado con CEDEARs descendi\u00f3 0,3% ($1.521) y, por su parte, el d\u00f3lar blue se mantuvo sin grandes cambios ($1.505). De esta forma, la brecha promedio finaliz\u00f3 en la zona del 5%.<\/p>\n<h3>Los futuros de d\u00f3lar al comp\u00e1s del spot<\/h3>\n<p>Los contratos a futuro del d\u00f3lar acompa\u00f1aron el movimiento del spot. En detalle, los contratos con vencimiento entre enero a marzo bajaron 2,2% y aquellos con vencimiento desde abril 2026 otro 2,0% Respecto a las devaluaciones impl\u00edcitas, el mercado cerr\u00f3 con una devaluaci\u00f3n del +1,4%, +4,1% y +7,0% para enero, febrero y marzo, respectivamente.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> (Cuenta Corriente + Efectivo + T\u00edtulos P\u00fablicos + Pases netos) \/ Dep\u00f3sitos Totales<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4431,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Kevin Pagnotta","image_url":"https:\/\/eco-latina.com.ar\/wp-content\/uploads\/2025\/08\/Fondo-cambiario-2.jpg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las compras del BCRA no alivian la escasez de pesos - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-16T21:12:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-16T21:12:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las compras del BCRA no alivian la escasez de pesos - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#blogposting\",\"name\":\"Las compras del BCRA no alivian la escasez de pesos - Ecolatina\",\"headline\":\"Las compras del BCRA no alivian la escasez de pesos\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Fondo-cambiario-2.jpg\",\"width\":1200,\"height\":580},\"datePublished\":\"2026-01-16T18:12:40-03:00\",\"dateModified\":\"2026-01-16T18:12:40-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#listItem\",\"name\":\"Las compras del BCRA no alivian la escasez de pesos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#listItem\",\"position\":3,\"name\":\"Las compras del BCRA no alivian la escasez de pesos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/\",\"name\":\"Las compras del BCRA no alivian la escasez de pesos - Ecolatina\",\"description\":\"La nueva Fase de Re-monetizaci\\u00f3n avanz\\u00f3 en la semana. El tipo de cambio spot finaliz\\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\\u00e1n a +-2,8% en febrero,\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Fondo-cambiario-2.jpg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#mainImage\",\"width\":1200,\"height\":580},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#mainImage\"},\"datePublished\":\"2026-01-16T18:12:40-03:00\",\"dateModified\":\"2026-01-16T18:12:40-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","description":"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,","canonical_url":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#blogposting","name":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","headline":"Las compras del BCRA no alivian la escasez de pesos","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/01\/Fondo-cambiario-2.jpg","width":1200,"height":580},"datePublished":"2026-01-16T18:12:40-03:00","dateModified":"2026-01-16T18:12:40-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#listItem","name":"Las compras del BCRA no alivian la escasez de pesos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#listItem","position":3,"name":"Las compras del BCRA no alivian la escasez de pesos","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#webpage","url":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","name":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","description":"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/01\/Fondo-cambiario-2.jpg","@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#mainImage","width":1200,"height":580},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#mainImage"},"datePublished":"2026-01-16T18:12:40-03:00","dateModified":"2026-01-16T18:12:40-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","og:description":"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,","og:url":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","article:published_time":"2026-01-16T21:12:40+00:00","article:modified_time":"2026-01-16T21:12:40+00:00","twitter:card":"summary_large_image","twitter:title":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","twitter:description":"La nueva Fase de Re-monetizaci\u00f3n avanz\u00f3 en la semana. El tipo de cambio spot finaliz\u00f3 en $1.441 (-2,4% respecto al viernes de la semana anterior) y ampli\u00f3 la distancia al techo de la banda al 8,1% ($1.546,18). El dato de inflaci\u00f3n publicado por diciembre implica que las bandas cambiarias se deslizar\u00e1n a +-2,8% en febrero,"},"aioseo_meta_data":{"post_id":"4430","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-16 21:29:09","updated":"2026-01-16 21:29:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas compras del BCRA no alivian la escasez de pesos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"Las compras del BCRA no alivian la escasez de pesos","link":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las compras del BCRA no alivian la escasez de pesos - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las compras del BCRA no alivian la escasez de pesos - Ecolatina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T21:12:40+00:00\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"Las compras del BCRA no alivian la escasez de pesos\",\"datePublished\":\"2026-01-16T21:12:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/\"},\"wordCount\":1800,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Fondo-cambiario-2.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/\",\"name\":\"Las compras del BCRA no alivian la escasez de pesos - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Fondo-cambiario-2.jpg\",\"datePublished\":\"2026-01-16T21:12:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Fondo-cambiario-2.jpg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Fondo-cambiario-2.jpg\",\"width\":1200,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/01\\\/16\\\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las compras del BCRA no alivian la escasez de pesos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","og_locale":"en_US","og_type":"article","og_title":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","og_url":"https:\/\/ecolatina.com\/en\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","og_site_name":"Ecolatina","article_published_time":"2026-01-16T21:12:40+00:00","author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"Las compras del BCRA no alivian la escasez de pesos","datePublished":"2026-01-16T21:12:40+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/"},"wordCount":1800,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/01\/Fondo-cambiario-2.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","url":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/","name":"Las compras del BCRA no alivian la escasez de pesos - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/01\/Fondo-cambiario-2.jpg","datePublished":"2026-01-16T21:12:40+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/01\/Fondo-cambiario-2.jpg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/01\/Fondo-cambiario-2.jpg","width":1200,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2026\/01\/16\/las-compras-del-bcra-no-alivian-la-escasez-de-pesos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"Las compras del BCRA no alivian la escasez de pesos"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/4430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=4430"}],"version-history":[{"count":0,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/4430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/4431"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=4430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=4430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=4430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}