{"id":4480,"date":"2026-02-13T17:44:55","date_gmt":"2026-02-13T20:44:55","guid":{"rendered":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/"},"modified":"2026-02-13T17:45:53","modified_gmt":"2026-02-13T20:45:53","slug":"la-contracara-de-la-compra-de-usd","status":"publish","type":"post","link":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","title":{"rendered":"La contracara de la compra de USD"},"content":{"rendered":"<p><em>El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares a los de julio del 2025.<\/em><\/p>\n<p><em>Las compras de divisas del BCRA (+USD 615 M en la semana) vienen teniendo como contrapartida un aumento de la demanda de bonos (v\u00eda ventas del Central en el secundario y licitaciones de Finanzas). Esto quiere decir que la demanda de dinero no se recuper\u00f3, sino que cay\u00f3 durante enero. Como resultado, el perfil de vencimientos en pesos del Tesoro viene creciendo y a un plazo menor al registrado a finales de 2025. Esto no representa un problema en el corto plazo, dado las se\u00f1ales de compromiso con el super\u00e1vit fiscal que presenta el Gobierno. No obstante, implica todo un desaf\u00edo para un 2027 que estar\u00e1 atravesado por las elecciones nacionales. Asimismo, se\u00f1ala cierta cautela por parte del mercado en torno al esquema cambiario.<\/em><\/p>\n<p><em>La estrategia monetaria-cambiaria es un Central expansivo o neutro y un Tesoro contractivo, pero la deuda que tiene como contrapartida la venta de d\u00f3lares en el spot por parte del sector privado se concentra en el corto plazo, demostrando una preferencia de los agentes por tener pesos en el corto ante cualquier sobresalto cambiario. En cualquier caso, en la medida que el sostenimiento del programa de compras avance como hasta ahora y mejoren las condiciones externas (menor Riesgo Pa\u00eds), el esquema cambiario ir\u00e1 ganando credibilidad y la demanda genuina de pesos ir\u00e1 apareciendo m\u00e1s pronto que tarde. <\/em><\/p>\n<p>\u00a0<\/p>\n<p>Queda atr\u00e1s una semana donde se profundiz\u00f3 la tendencia que viene presentando el plano cambiario-monetario desde el arranque de 2026. En concreto, <strong>el tipo de cambio spot <\/strong>aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, <strong>la distancia al techo de la banda <\/strong>super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares a los de finales de julio del 2025.<\/p>\n<p>Asimismo, <strong>el BCRA redonde\u00f3 una semana con las compras m\u00e1s abultadas <\/strong>desde el inicio de la nueva Fase de Remonetizaci\u00f3n. El Central sum\u00f3 dos compras importantes por USD 176 M el lunes y USD 214 M el mi\u00e9rcoles, siendo esta \u00faltima la mayor compra diaria desde en lo que va del a\u00f1o. De esta forma, el ritmo de compras se aceler\u00f3 a un promedio diario de USD 93 M en febrero desde USD 58 M en enero. Con todo, la acumulaci\u00f3n alcanza los USD 932 M en el mes y USD 2.090 M en lo que va del a\u00f1o.<\/p>\n<p>Hace ya unas semanas venimos mencionando <strong>los drivers detr\u00e1s de las compras del Central: 1)<\/strong> Una mayor liquidaci\u00f3n del sector agropecuario producto del ingreso de la cosecha fina, algo que se hab\u00eda reducido a m\u00ednimos posterior al vencimiento de la eliminaci\u00f3n temporal de las retenciones en septiembre del a\u00f1o pasado; <strong>2)<\/strong> Un crecimiento de los pr\u00e9stamos en d\u00f3lares, aumentando USD 1.200 M durante enero (se excluye pr\u00e9stamos por tarjeta); y <strong>3)<\/strong> La liquidaci\u00f3n remanente de las Obligaciones Negociables en d\u00f3lares, que entre noviembre y enero acumularon una colocaci\u00f3n de USD 6.500 M, pero un ingreso neto en el mercado de cambios de apenas USD 2.500 M hasta diciembre del 2025.<\/p>\n<p>Por otro lado, la cuesti\u00f3n pasaba por ver qu\u00e9 ocurr\u00eda con <strong>la demanda de dinero.<\/strong> Pasada las elecciones, la elevada cobertura cambiaria que tom\u00f3 el mercado comenz\u00f3 a mermar, fruto de una menor incertidumbre tras los resultados de los comicios. Pero no s\u00f3lo eso, sino que la modificaci\u00f3n del r\u00e9gimen cambiario y las se\u00f1ales cada vez m\u00e1s contundentes de compras del BCRA fueron un factor decisivo para que en este tiempo el esquema cambiario gane credibilidad. Un punto para tener en cuenta es que, a pesar de las restricciones cambiarias vigentes que suavizan el impacto, el d\u00f3lar se est\u00e1 debilitando a nivel global y a la par se est\u00e1n fortaleciendo las monedas emergentes (el Real en t\u00e9rminos nominales se fortaleci\u00f3 m\u00e1s del 5% en lo que va de 2026), din\u00e1micas donde el peso no es la excepci\u00f3n. Por tanto, el tipo de cambio real pas\u00f3 de subir cerca de un 20% entre el cambio de esquema en abril a diciembre del 2025, a caer poco m\u00e1s del 4% en lo que va del a\u00f1o en medio de la nueva Fase y el contexto internacional. \u00a0<\/p>\n<p>Volviendo al contexto local, por el momento <strong>las compras de divisas del BCRA no tuvieron como contrapartida un fuerte aumento en la demanda de dinero<\/strong> (que se reflejar\u00eda en un crecimiento de los agregados), por lo cual la liquidez remanente se direccion\u00f3 hacia bonos del Tesoro. Comentamos en el informe del viernes anterior que la Base Monetaria sin estacionalidad cay\u00f3 0,6% mensual en enero y que esto se dio a pesar de que el Central inyect\u00f3 pesos por las compras de divisas al sector privado (+$1,6 bn). No obstante, tambi\u00e9n dec\u00edamos que estos pesos se retiraban mediante las licitaciones y el super\u00e1vit fiscal del Tesoro, y la esterilizaci\u00f3n (venta de bonos en el mercado secundario) por parte del Central a cambio de cobertura (d\u00f3lar linked) que incentive la venta de divisas en el spot y de instrumentos denominados en moneda local.<\/p>\n<p>Reflejando este hecho, <strong>los diferentes agregados monetarios<\/strong> (<em>proxy <\/em>de la demanda dinero) <strong>cayeron durante el mes pasado<\/strong>. El M2 Privado Transaccional (circulante + dep\u00f3sitos no remunerados), medici\u00f3n que utiliza el BCRA para aproximar la demanda de dinero y que estima crecer\u00eda 0,6 p.p. con relaci\u00f3n al PIB en 2026, cay\u00f3 a 1,0% mensual sin estacionalidad, el M2 Privado (circulante + dep\u00f3sitos sin excluir remunerados) se desplom\u00f3 5,2% s.e. y el M3 Privado (M2 + plazos fijos) baj\u00f3 1,6% s.e.<\/p>\n<p>La buena noticia es que <strong>los pr\u00e9stamos en pesos crecieron por segundo mes consecutivo<\/strong>, algo que no ocurr\u00eda desde el pasado agosto. En detalle, los cr\u00e9ditos al sector privado en moneda dom\u00e9stica subieron 1,9% mensual (s.e.), impulsados por un crecimiento de los pr\u00e9stamos comerciales (adelantos + documentos) de 3,3% y por una recuperaci\u00f3n de los cr\u00e9ditos otorgados para el consumo (+1,0%) que cortaron cuatro meses consecutivos a la baja. Estar\u00e1 por verse si est\u00e1 recuperaci\u00f3n es una racha pasajera o estamos hablando de una recuperaci\u00f3n de la tendencia creciente que supo registrar el cr\u00e9dito en pesos, la cual deber\u00eda venir asociada a una relajaci\u00f3n al menos parcial de la situaci\u00f3n de moras de las familias y las empresas. Esto es porque m\u00e1s all\u00e1 de las condiciones macro que influyeron negativamente (volatilidad de tasas, estancamiento del consumo y de los ingresos al cierre de 2025) en el aumento de la mora de las familias y las empresas, los bancos optaron por reducir la hoja de balance debido al deterioro de las carteras y la estrechez de liquidez.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-20733\" src=\"https:\/\/eco-latina.com.ar\/wp-content\/uploads\/2026\/02\/Agregados.png\" alt=\"\" width=\"1280\" height=\"720\" \/><\/p>\n<p>Retomando la estrategia monetaria, <strong>Finanzas obtuvo un rollover nuevamente por encima del 120%<\/strong>. De esta forma, retir\u00f3 del mercado $1,7 bn, cifra casi equivalente a lo que viene inyectando el Central por las compras en el mercado desde el d\u00eda posterior a la \u00faltima licitaci\u00f3n de enero ($1,5 bn). Hoy se liquida la licitaci\u00f3n y es probable que los bancos tengan que pedir pesos al BCRA para cumplimentar la subasta, tal como ocurri\u00f3 durante el pasado 30 de enero cuando solicitaron cerca de $0,9 bn ($0,7 bn neto de Pases por simult\u00e1neas) y la tasa comenz\u00f3 a subir como consecuencia de la escasez de pesos. Veremos si en esta oportunidad la leve flexibilizaci\u00f3n de encajes introducida, que permite que los bancos incumplan 5% de los encajes en el mes (aunque debe sobrecumplirse al mes siguiente, es decir, 105%), es suficiente para suavizar episodios de iliquidez (hoy la tasa de cauci\u00f3n trep\u00f3 a 35% TNA PP desde 28% TNA P ayer) y evitar que se transmita a las tasas en pesos del mercado.<\/p>\n<p>Otro factor a considerar es la suerte de <strong>\u201cdominancia monetaria\u201d<\/strong> que presenta el curso de la estrategia actual. Si los pesos emitidos por el BCRA como contrapartida de la compra de divisas son retirados v\u00eda bonos (venta en el secundario por el BCRA y licitaciones de Finanzas), esto implica un <strong>perfil de vencimientos en pesos <\/strong>del Tesoro creciente. Veamos en n\u00fameros. Tomando la \u00faltima licitaci\u00f3n y comparando con el perfil en pesos de diciembre del 2025, los vencimientos aumentaron $20,2 bn hasta finales de a\u00f1o y $53,5 bn hasta junio del 2027, previo a las elecciones presidenciales que tendr\u00e1n lugar dicho a\u00f1o. Asimismo, si bien el premio de las licitaciones viene bajando, el perfil de vencimiento de los instrumentos a tasa fija sigue concentr\u00e1ndose mayormente en el corto plazo. El plazo promedio ponderado se acerca a los cuatro meses en lo que va del a\u00f1o, por debajo de los cerca de ocho meses que mostr\u00f3 en las \u00faltimas tres licitaciones de finales de 2025.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-20734\" src=\"https:\/\/eco-latina.com.ar\/wp-content\/uploads\/2026\/02\/Fiscal.png\" alt=\"\" width=\"1280\" height=\"720\" \/><\/p>\n<p>Dicho esto, m\u00e1s all\u00e1 de la cuesti\u00f3n sobre los intereses capitalizados y su registro contable, <strong>no vemos un gran problema fiscal de fondo<\/strong> (siempre y cuando no aparezcan factores ex\u00f3genos que rompan el equilibrio del esquema) m\u00e1s all\u00e1 de una eventual suba de la deuda p\u00fablica en el margen. Creemos que al menos para este a\u00f1o el sendero de super\u00e1vit fiscal y el compromiso demostrado por el Gobierno en esta materia permiten despejar cualquier tipo de ruido en este frente. De todas formas, el sostenimiento de esta estrategia en el mediano plazo impondr\u00e1 un desaf\u00edo para un 2027 atravesado por la t\u00edpica incertidumbre electoral.<\/p>\n<p>No obstante, s\u00ed <strong>se\u00f1ala cierta cautela en el frente cambiario<\/strong>. La estrategia monetaria-cambiaria es un <strong>Central expansivo o neutro y un Tesoro contractivo<\/strong>, pero la deuda que tiene como contrapartida la venta de d\u00f3lares en el spot por parte del sector privado se concentra en el corto plazo, demostrando una preferencia de los agentes por tener pesos en el corto ante cualquier sobresalto cambiario. En cualquier caso, en la medida que el sostenimiento del programa de compras avance como hasta ahora y mejoren las condiciones externas (menor Riesgo Pa\u00eds), el esquema cambiario ir\u00e1 ganando credibilidad y la demanda genuina de pesos ir\u00e1 apareciendo m\u00e1s pronto que tarde.<\/p>\n<h3>Baja del d\u00f3lar oficial<\/h3>\n<p>El tipo de cambio spot finaliz\u00f3 en $1.399,5 (-2,3% semanal) y ampli\u00f3 la distancia al techo de la banda (13,3%) al valor m\u00e1s elevado desde julio del 2025. Por otro lado, el BCRA compr\u00f3 USD 615 M en la semana y las Reservas Netas (Brutas \u2013 Swap CH y USA \u2013 Encajes \u2013 REPOs \u2013 SEDESA) se ubicar\u00edan en terreno negativo por USD 600 M.<\/p>\n<h3>La brecha cambiaria se estabiliza<\/h3>\n<p>Los d\u00f3lares alternativos finalizaron a la baja: el d\u00f3lar minorista baj\u00f3 2,2% ($1.421) respecto al viernes de la semana anterior, el d\u00f3lar MEP operado con AL30 cay\u00f3 2,2% ($1.419), el CCL operado con CEDEARs descendi\u00f3 1,0% ($1.473) y, por el contrario, el blue aument\u00f3 0,3% ($1.440). De esta forma, la brecha promedio finaliz\u00f3 en la zona del 3%.<\/p>\n<h3>Los futuros de d\u00f3lar bajan<\/h3>\n<p>Los contratos a futuro del d\u00f3lar acompa\u00f1aron al movimiento del spot. En detalle, los contratos con vencimiento entre febrero a abril recortaron 2,5% y aquellos con vencimiento desde mayo 2026 bajaron 2,6%. Respecto a las devaluaciones impl\u00edcitas, el mercado cerr\u00f3 con una devaluaci\u00f3n del +1,3%, +3,9% y +6,2% para febrero, marzo y abril, respectivamente.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4484,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"author_name":"Kevin Pagnotta","image_url":"https:\/\/eco-latina.com.ar\/wp-content\/uploads\/2025\/08\/Fondo-cambiario-1.jpg","_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AppVisor Blog Bot\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La contracara de la compra de USD - Ecolatina\" \/>\n\t\t<meta property=\"og:description\" content=\"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-02-13T20:44:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-13T20:45:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La contracara de la compra de USD - Ecolatina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#blogposting\",\"name\":\"La contracara de la compra de USD - Ecolatina\",\"headline\":\"La contracara de la compra de USD\",\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Fondo-cambiario-1-2.jpg\",\"width\":1200,\"height\":580},\"datePublished\":\"2026-02-13T17:44:55-03:00\",\"dateModified\":\"2026-02-13T17:45:53-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#webpage\"},\"articleSection\":\"Sin categor\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Sin categor\\u00eda\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#listItem\",\"name\":\"La contracara de la compra de USD\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#listItem\",\"position\":3,\"name\":\"La contracara de la compra de USD\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/category\\\/sin-categoria\\\/#listItem\",\"name\":\"Sin categor\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\",\"name\":\"AppVisor Blog Bot\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#webpage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/\",\"name\":\"La contracara de la compra de USD - Ecolatina\",\"description\":\"El tipo de cambio spot aceler\\u00f3 la tendencia a la baja y finaliz\\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\\u00e1s bajo desde noviembre del a\\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\\u00f3 los dos d\\u00edgitos (13,3%) y se ubic\\u00f3 en niveles similares\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Fondo-cambiario-1-2.jpg\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#mainImage\",\"width\":1200,\"height\":580},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#mainImage\"},\"datePublished\":\"2026-02-13T17:44:55-03:00\",\"dateModified\":\"2026-02-13T17:45:53-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\\u00e9gico para la toma de decisiones\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La contracara de la compra de USD - Ecolatina","description":"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares","canonical_url":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#blogposting","name":"La contracara de la compra de USD - Ecolatina","headline":"La contracara de la compra de USD","author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-2.jpg","width":1200,"height":580},"datePublished":"2026-02-13T17:44:55-03:00","dateModified":"2026-02-13T17:45:53-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#webpage"},"isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#webpage"},"articleSection":"Sin categor\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecolatina.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","position":2,"name":"Sin categor\u00eda","item":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#listItem","name":"La contracara de la compra de USD"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#listItem","position":3,"name":"La contracara de la compra de USD","previousItem":{"@type":"ListItem","@id":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/#listItem","name":"Sin categor\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/en\/#organization","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","url":"https:\/\/ecolatina.com\/en\/"},{"@type":"Person","@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/","name":"AppVisor Blog Bot"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#webpage","url":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","name":"La contracara de la compra de USD - Ecolatina","description":"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ecolatina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#breadcrumblist"},"author":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"creator":{"@id":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-2.jpg","@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#mainImage","width":1200,"height":580},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#mainImage"},"datePublished":"2026-02-13T17:44:55-03:00","dateModified":"2026-02-13T17:45:53-03:00"},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/en\/#website","url":"https:\/\/ecolatina.com\/en\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","inLanguage":"en-US","publisher":{"@id":"https:\/\/ecolatina.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ecolatina - Tu socio estrat\u00e9gico para la toma de decisiones","og:type":"article","og:title":"La contracara de la compra de USD - Ecolatina","og:description":"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares","og:url":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","article:published_time":"2026-02-13T20:44:55+00:00","article:modified_time":"2026-02-13T20:45:53+00:00","twitter:card":"summary_large_image","twitter:title":"La contracara de la compra de USD - Ecolatina","twitter:description":"El tipo de cambio spot aceler\u00f3 la tendencia a la baja y finaliz\u00f3 en $1.399,5 (-2,3% semanal), quebrando la barrera de los $1.400 y alcanzando el valor nominal m\u00e1s bajo desde noviembre del a\u00f1o pasado. Como consecuencia, la distancia al techo de la banda super\u00f3 los dos d\u00edgitos (13,3%) y se ubic\u00f3 en niveles similares"},"aioseo_meta_data":{"post_id":"4480","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-02-13 21:04:23","updated":"2026-02-13 21:04:23","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/\" title=\"Sin categor\u00eda\">Sin categor\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa contracara de la compra de USD\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecolatina.com\/en"},{"label":"Sin categor\u00eda","link":"https:\/\/ecolatina.com\/en\/category\/sin-categoria\/"},{"label":"La contracara de la compra de USD","link":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La contracara de la compra de USD - Ecolatina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La contracara de la compra de USD - Ecolatina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecolatina\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T20:44:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T20:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AppVisor Blog Bot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:site\" content=\"@Ecolatina_Arg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AppVisor Blog Bot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/\"},\"author\":{\"name\":\"AppVisor Blog Bot\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\"},\"headline\":\"La contracara de la compra de USD\",\"datePublished\":\"2026-02-13T20:44:55+00:00\",\"dateModified\":\"2026-02-13T20:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/\"},\"wordCount\":1931,\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Fondo-cambiario-1-2.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/\",\"name\":\"La contracara de la compra de USD - Ecolatina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Fondo-cambiario-1-2.jpg\",\"datePublished\":\"2026-02-13T20:44:55+00:00\",\"dateModified\":\"2026-02-13T20:45:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Fondo-cambiario-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Fondo-cambiario-1-2.jpg\",\"width\":1200,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/2026\\\/02\\\/13\\\/la-contracara-de-la-compra-de-usd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ecolatina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La contracara de la compra de USD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#website\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"name\":\"Ecolatina\",\"description\":\"Tu socio estrat\u00e9gico para la toma de decisiones \",\"publisher\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecolatina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#organization\",\"name\":\"Ecolatina\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"contentUrl\":\"https:\\\/\\\/ecolatina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Ecolatina_logo_01-verde-sin-tagline.png\",\"width\":1008,\"height\":260,\"caption\":\"Ecolatina\"},\"image\":{\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ecolatina_Arg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ecolatina\\\/?originalSubdomain=ar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ecolatina.com\\\/#\\\/schema\\\/person\\\/ff70142206e33eb083069905ccc586b0\",\"name\":\"AppVisor Blog Bot\",\"url\":\"https:\\\/\\\/ecolatina.com\\\/en\\\/author\\\/appvisorblogbot\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La contracara de la compra de USD - Ecolatina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","og_locale":"en_US","og_type":"article","og_title":"La contracara de la compra de USD - Ecolatina","og_url":"https:\/\/ecolatina.com\/en\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","og_site_name":"Ecolatina","article_published_time":"2026-02-13T20:44:55+00:00","article_modified_time":"2026-02-13T20:45:53+00:00","og_image":[{"width":1200,"height":580,"url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-1.jpg","type":"image\/jpeg"}],"author":"AppVisor Blog Bot","twitter_card":"summary_large_image","twitter_creator":"@Ecolatina_Arg","twitter_site":"@Ecolatina_Arg","twitter_misc":{"Written by":"AppVisor Blog Bot","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#article","isPartOf":{"@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/"},"author":{"name":"AppVisor Blog Bot","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0"},"headline":"La contracara de la compra de USD","datePublished":"2026-02-13T20:44:55+00:00","dateModified":"2026-02-13T20:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/"},"wordCount":1931,"publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"image":{"@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-2.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","url":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/","name":"La contracara de la compra de USD - Ecolatina","isPartOf":{"@id":"https:\/\/ecolatina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#primaryimage"},"image":{"@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#primaryimage"},"thumbnailUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-2.jpg","datePublished":"2026-02-13T20:44:55+00:00","dateModified":"2026-02-13T20:45:53+00:00","breadcrumb":{"@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#primaryimage","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-2.jpg","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2026\/02\/Fondo-cambiario-1-2.jpg","width":1200,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/ecolatina.com\/2026\/02\/13\/la-contracara-de-la-compra-de-usd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ecolatina.com\/"},{"@type":"ListItem","position":2,"name":"La contracara de la compra de USD"}]},{"@type":"WebSite","@id":"https:\/\/ecolatina.com\/#website","url":"https:\/\/ecolatina.com\/","name":"Ecolatina","description":"Tu socio estrat\u00e9gico para la toma de decisiones","publisher":{"@id":"https:\/\/ecolatina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecolatina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecolatina.com\/#organization","name":"Ecolatina","url":"https:\/\/ecolatina.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","contentUrl":"https:\/\/ecolatina.com\/wp-content\/uploads\/2023\/05\/Ecolatina_logo_01-verde-sin-tagline.png","width":1008,"height":260,"caption":"Ecolatina"},"image":{"@id":"https:\/\/ecolatina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Ecolatina_Arg","https:\/\/www.linkedin.com\/company\/ecolatina\/?originalSubdomain=ar"]},{"@type":"Person","@id":"https:\/\/ecolatina.com\/#\/schema\/person\/ff70142206e33eb083069905ccc586b0","name":"AppVisor Blog Bot","url":"https:\/\/ecolatina.com\/en\/author\/appvisorblogbot\/"}]}},"_links":{"self":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/4480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/comments?post=4480"}],"version-history":[{"count":1,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/4480\/revisions"}],"predecessor-version":[{"id":4483,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/posts\/4480\/revisions\/4483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media\/4484"}],"wp:attachment":[{"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/media?parent=4480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/categories?post=4480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolatina.com\/en\/wp-json\/wp\/v2\/tags?post=4480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}